{"id":10424,"date":"2009-05-07T02:38:53","date_gmt":"2009-05-07T01:38:53","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=10424"},"modified":"2009-05-07T03:45:33","modified_gmt":"2009-05-07T02:45:33","slug":"una-pietra-tombale-sulla-class-action-retroattiva","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2009\/05\/07\/una-pietra-tombale-sulla-class-action-retroattiva\/","title":{"rendered":"Una pietra tombale sulla class action retroattiva"},"content":{"rendered":"<p><a href=\"http:\/\/www.lastampa.it\/redazione\/cmsSezioni\/economia\/200905articoli\/43456girata.asp\">Via Lastampa.it<\/a><\/p>\n<blockquote><p>\nLa Class action sar\u00e0 introdotta senza valore retroattivo. \u00abC\u2019\u00e8 un emendamento in questo senso del senatore Alberto Balboni (Pdl, ndr)\u00bb, riferisce il relatore al disegno di legge sviluppo, Antonio Paravia (Pdl) a margine dei lavori in senato. Secondo il testo del ddl uscito dalla commissione industria sono possibili azioni di classi contro frodi messe in atto a partire dal luglio 2008. Con l\u2019emendamento della maggioranza si cancellerebbe anche questa breve retroattivit\u00e0.<\/p>\n<p>L\u2019azione di classe arriver\u00e0 in Italia ma varr\u00e0 solo per gli illeciti che verranno commessi dopo l\u2019approvazione del Collegato Sviluppo, ora all\u2019esame del Senato e che comunque vedr\u00e0 un altro passaggio alla Camera. L\u2019ennesimo rinvio \u00e8 sancito da un emendamento della maggioranza (a firmarlo \u00e8 Alberto Balboni del Pdl) al disegno di legge Sviluppo che contiene norme sull\u2019energia e il nucleare e sulla competitivit\u00e0 delle imprese italiane. La proposta di modifica deve avere ancora l\u2019ok dell\u2019Aula di Palazzo Madama, che ha cominciato a votare gli emendamenti al ddl oggi pomeriggio, ma sembra evidente che su questa proposta dovrebbe convergere il s\u00ec di gran parte della maggioranza \u00abperch\u00e8 la retroattivit\u00e0 delle norme giuridiche &#8211; commenta il relatore Antonio Paravia del Pdl &#8211; \u00e8 sempre molto difficile da accettare\u00bb.<br \/>\n<!--more--><\/p>\n<p>Un principio dunque di &#8220;correttezza&#8221; giuridica che rischia di passare per\u00f2 sopra le aspettative di migliaia di consumatori frodati dai grandi crac che hanno investito il Paese negli ultimi anni, da Cirio a Parmalat, per citare le storie pi\u00f9 importanti. Anche se, per essere precisi, il testo licenziato dalla Commissione Industria del Senato gi\u00e0 limitava parecchio la retroattivit\u00e0 ammettendola solo dal luglio 2008. Furiosa l\u2019opposizione. Elio Lannutti dell\u2019Idv sottolinea che \u00abogni altro rinvio della class action significa continuare ad andare a braccetto con bancarottieri e truffatori\u00bb. \u00c8 una \u00abscelta inaccettabile\u00bb per il capogruppo dei senatori Pd Anna Finocchiaro. Luigi Zanda, sempre del Pd, commenta: \u00abSu quelle vicende che negli ultimi anni hanno contribuito alla crisi italiana, il centrodestra vuol far calare definitivamente il sipario\u00bb.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Via Lastampa.it La Class action sar\u00e0 introdotta senza valore retroattivo. \u00abC\u2019\u00e8 un emendamento in questo senso del senatore Alberto Balboni (Pdl, ndr)\u00bb, riferisce il relatore al disegno di legge sviluppo, Antonio Paravia (Pdl) a margine dei lavori in senato. Secondo il testo del ddl uscito dalla commissione industria sono possibili azioni di classi contro frodi &#8230; <a title=\"Una pietra tombale sulla class action retroattiva\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2009\/05\/07\/una-pietra-tombale-sulla-class-action-retroattiva\/\" aria-label=\"Per saperne di pi\u00f9 su Una pietra tombale sulla class action retroattiva\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,17,32],"tags":[877,878],"class_list":["post-10424","post","type-post","status-publish","format-standard","hentry","category-diritti","category-economia","category-pensieri","tag-class-action","tag-parmalat"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/10424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=10424"}],"version-history":[{"count":4,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/10424\/revisions"}],"predecessor-version":[{"id":10429,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/10424\/revisions\/10429"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=10424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=10424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=10424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}