{"id":1223,"date":"2007-02-05T17:32:58","date_gmt":"2007-02-05T16:32:58","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/2007\/02\/05\/una-stanza-piccola-buia-e-soprattutto-segregata\/"},"modified":"2007-02-05T17:51:03","modified_gmt":"2007-02-05T16:51:03","slug":"una-stanza-piccola-buia-e-soprattutto-segregata","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2007\/02\/05\/una-stanza-piccola-buia-e-soprattutto-segregata\/","title":{"rendered":"Una stanza piccola buia e soprattutto segregata"},"content":{"rendered":"<p>Della sua <a target=\"_blank\" href=\"http:\/\/www.pasteris.it\/blog\/2006\/08\/09\/il-nuovo-che-avanza\/\">nomina ridicola<\/a> si era gi\u00e0 riso tristemente a suo tempo.<\/p>\n<p>Ora ha dato largo ai pensieri della sua base votante: quella che vuole che sembra cambi tutto e che invece non  cambi nulla nel concreto:<\/p>\n<blockquote><p>Lo spettacolo deve continuare. Ho sentito dire che il calcio dovrebbe fermarsi per un anno, ma parlare in questo modo significa essere esaltati e irresponsabili  &#8230; Il calcio \u00e8 un\u2019industria che paga i suoi prezzi: non \u00e8 che la Fiat ha dovuto fermare le macchine per rilanciarsi . Ci sono momenti in cui ci si deve fermare e sono stato d\u2019accordissimo con Pancalli questa volta. Ma i morti li abbiamo voluti noi? Purtroppo fanno parte di questo grandissimo movimento.<\/p><\/blockquote>\n<p>Ci sarebbero gi\u00e0 delle regole, ma bisognerebbe farle rispettare &#8230; esempio non utilizzare stadi pietosi o evitare di foraggiare gli ultras pi\u00f9 biechi.<\/p>\n<p>Per favore non parlate per molto di questo calcio e rinchiudete in una stanza senza finestre Matarrerese. Limitando il cibo a disposizione del suddetto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Della sua nomina ridicola si era gi\u00e0 riso tristemente a suo tempo. Ora ha dato largo ai pensieri della sua base votante: quella che vuole che sembra cambi tutto e che invece non cambi nulla nel concreto: Lo spettacolo deve continuare. Ho sentito dire che il calcio dovrebbe fermarsi per un anno, ma parlare in &#8230; <a title=\"Una stanza piccola buia e soprattutto segregata\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2007\/02\/05\/una-stanza-piccola-buia-e-soprattutto-segregata\/\" aria-label=\"Per saperne di pi\u00f9 su Una stanza piccola buia e soprattutto segregata\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[415,2157,90,131,561],"class_list":["post-1223","post","type-post","status-publish","format-standard","hentry","tag-arte","tag-blog","tag-calcio","tag-fiat","tag-tempo"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/1223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=1223"}],"version-history":[{"count":0,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/1223\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=1223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=1223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=1223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}