{"id":12750,"date":"2009-09-07T13:26:48","date_gmt":"2009-09-07T11:26:48","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=12750"},"modified":"2009-09-07T13:26:48","modified_gmt":"2009-09-07T11:26:48","slug":"ricchi-e-impegnati","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2009\/09\/07\/ricchi-e-impegnati\/","title":{"rendered":"Ricchi e impegnati"},"content":{"rendered":"<p><a href=\"http:\/\/www.lsdi.it\/2009\/09\/06\/anche-sul-web-i-piu-impegnati-politicamente-sono-i-cittadini-piu-ricchi-e-piu-scolarizzati-per-ora\/\">Via LSDI<\/a><\/p>\n<blockquote><p>Negli Usa Internet non ha ancora cambiato profondamente le abitudini politiche dei cittadini. Risultato? Globalmente i pi\u00f9 ricchi e i pi\u00f9 scolarizzati restano gli individui pi\u00f9 impegnati. Anche se forse le reti sociali potrebbero modificare questa situazione.<br \/>\nE\u2019 quello che sostengono gli esperti del \u00a0<a href=\"http:\/\/pewresearch.org\/pubs\/1328\/online-political-civic-engagement-activity?src=prc-latest&amp;proj=peoplepress\" target=\"_blank\">Centro di ricerca Pew<\/a> che &#8211;\u00a0  segnala <a href=\"http:\/\/www.atelier.fr\/statistiques\/10\/03092009\/engagement-politique-internet-20-blog-reseau-social--jeune-civique-38650-.html#xtor=EPR-233-233-20090903\">atelier.fr<\/a> \u2013 hanno condotto uno studio su 2.000 cittadini americani. Qui sotto la tabella  relativa a fasce di reddito\/impegno pubblico.<br \/>\n<a href=\"http:\/\/www.lsdi.it\/wp-content\/pew1.jpg\"><img decoding=\"async\" title=\"pew1\" src=\"http:\/\/www.lsdi.it\/wp-content\/pew1.jpg\" alt=\"pew1\" width=\"500\" \/><\/a><\/p>\n<p><!--more--><\/p>\n<p>Secondo la ricerca, pi\u00f9 di un quarto degli utenti si servono dei servizi cosiddetti &#8220;2.0&#8221; per condurre attivit\u00e0 politiche o civiche.<br \/>\nDal virtuale al reale<\/p>\n<p>Per i ricercatori l\u2019 impegno pu\u00f2 consistere anche semplicemente nell\u2019 aggiungere un esponente politico nella sua lista di contatti su Facebook. Ma pu\u00f2 arrivare fino a condurre una campagna virtuale di sostegno al proprio candidato preferito. Una tendenza interessante, secondo atelier.fr: i giovani fra i 18 e i 24 anni, tradizionalmente poco impegnati in politica, hanno una maggiore tendenza a utilizzare i blog e le reti sociali per esprimersi, anche su questioni di carattere politico.<\/p>\n<p>Secondo i ricercatori, il web collaborativo potrebbe contribuire a far impegnare politicamente i giovani anche nella vita reale. Inoltre le persone che si impegnano politicamente attraverso le reti sociali riflettono una immagine della societ\u00e0 pi\u00f9 vicina alla realt\u00e0 in termini di reddito e di educazione.<\/p>\n<p>Previsioni troppo ottimistiche?<\/p>\n<p>Gli autori sottolineano che sarebbe interessante sapere come i giovani impegnati utilizzeranno in futuro l\u2019 attitudine partecipativa di Internet: il web cambiera il carattere socio-economico dell\u2019 impegno dei cittadini? O le tecnologie creeranno delle nuove barriere per le classi svantaggiate? Altra questione sollevata: la tendenza si confermer\u00e0 nei prossimi anni o si tratta di una fase momentanea?<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Via LSDI Negli Usa Internet non ha ancora cambiato profondamente le abitudini politiche dei cittadini. Risultato? Globalmente i pi\u00f9 ricchi e i pi\u00f9 scolarizzati restano gli individui pi\u00f9 impegnati. Anche se forse le reti sociali potrebbero modificare questa situazione. E\u2019 quello che sostengono gli esperti del \u00a0Centro di ricerca Pew che &#8211;\u00a0 segnala atelier.fr \u2013 &#8230; <a title=\"Ricchi e impegnati\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2009\/09\/07\/ricchi-e-impegnati\/\" aria-label=\"Per saperne di pi\u00f9 su Ricchi e impegnati\">Leggi tutto<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,32],"tags":[609,210,919],"class_list":["post-12750","post","type-post","status-publish","format-standard","hentry","category-diritti","category-pensieri","tag-denaro","tag-lsdi","tag-politici"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/12750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=12750"}],"version-history":[{"count":2,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/12750\/revisions"}],"predecessor-version":[{"id":12752,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/12750\/revisions\/12752"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=12750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=12750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=12750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}