{"id":12821,"date":"2009-09-10T02:03:47","date_gmt":"2009-09-10T00:03:47","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=12821"},"modified":"2009-09-10T02:03:47","modified_gmt":"2009-09-10T00:03:47","slug":"i-blogger-tedeschi-lanciano-un-manifesto-per-il-giornalismo-on-line","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2009\/09\/10\/i-blogger-tedeschi-lanciano-un-manifesto-per-il-giornalismo-on-line\/","title":{"rendered":"I blogger tedeschi lanciano un manifesto per il giornalismo on-line"},"content":{"rendered":"<p><a href=\"http:\/\/pennedigitali.libero.it\/2009\/dalla-germania-il-manifesto-del-giornalismo-online\/#more-867\">Via Penne digitali<\/a><\/p>\n<blockquote><p>Diciasette dichiarazioni sul giornalismo di oggi,\u00a0raccolte in un Internet Manifesto, da\u00a0un gruppo di\u00a0autori\/blogger tedeschi, tutti esperti di <em>\u201cNetz\u201d<\/em>. Un documento interessante che Jaff Javis\u00a0si \u00e8 preso la\u00a0briga di <a href=\"http:\/\/twitter.com\/jeffjarvis\">tradurre in inglese, tramite Twitter<\/a>.<\/p><\/blockquote>\n<p><a href=\"http:\/\/www.internet-manifesto.org\/\">Internet Manifesto: How journalism works today. Seventeen declarations<\/a><\/p>\n<blockquote><p>1. &#8220;Internet \u00e8 diverso&#8221; Il nuovo mezzo di comunicazione \u00e8 molto differente rispetto agli altri media. Chi vuol lavorare nel campo dell&#8217;informazione deve adattare i propri metodi di lavoro alla realt\u00e0 tecnologica di oggi invece di ignorare e contestare il mondo multimediale. Bisogna produrre prodotti giornalisti nuovi e migliori.<\/p>\n<p>2. &#8220;Internet \u00e8 un impero mediatico tascabile&#8221; Grazie a internet \u00e8 possibile fare dell&#8217;ottimo giornalismo anche senza immensi investimenti. Il web riorganizza le strutture esistenti dei media abbattendendo gli antichi confini che esistevano tra giornali, televisione, radio etc.<\/p>\n<p><!--more--><\/p>\n<p>3.&#8221;Internet \u00e8 la nostra societ\u00e0 e la nostra societ\u00e0 \u00e8 internet&#8221; Wikipedia, YouTube e i social network sono diventati una parte della vita quotidiana per la maggioranza delle persone nel mondo occidentale. I mezzi di comunicazione, se intendono sopravvivere alla rivoluzione tecnologica contemporanea, devono capire i legittimi interessi dei nuovi utenti e abbracciare le loro forme di comunicazione.<\/p>\n<p>4. &#8220;La libert\u00e0 di internet \u00e8 inviolabile&#8221; Il giornalismo del XXI secolo che comunica digitalmente deve adattarsi all&#8217; architettura aperta di Internet. Non \u00e8 ammissibile che si limiti questa libert\u00e0 in nome di interessi particolari commerciali o politici, spesso presentati come interessi generali. Bloccare parzialmente l&#8217;accesso a internet mette a repentaglio il libero flusso delle informazioni e il diritto fondamentale di informarsi.<\/p>\n<p>5. &#8220;Internet \u00e8 la vittoria dell&#8217;informazione&#8221; Per la prima volta grazie a Internet l&#8217;utente pu\u00f2 scegliere realmente come informarsi e attraverso i motori di ricerca attingere a un patrimonio d&#8217;informazione immenso.<\/p>\n<p>6. &#8220;I cambiamenti apportati da Internet migliorano il giornalismo&#8221; Grazie a internet il giornalismo pu\u00f2 svolgere un&#8217;azione socio-educativa completamente nuova. Ci\u00f2 significa presentare notizie in continuo cambiamento attraverso un processo inarrestabile. Chi vuol praticare il giornalismo deve essere stimolato da un nuovo idealismo e capire che le risorse offerte da internet sono un incredibile stimolo a migliorare.<\/p>\n<p>7. &#8220;La rete richiede collegamenti&#8221; La rete \u00e8 fatta di collegamenti. Chi non li usa si autoesclude dal dibattito sociale e ci\u00f2 vale anche per i sitiweb dei tradizionali mezzi di comunicazione.<\/p>\n<p>8. &#8220;Linkare premia, citare abbellisce&#8221; Chi fa giornalismo online deve offrire all&#8217;utente un prodotto sempre pi\u00f9 completo. Linkare le fonti e citarle permette di conoscere direttamente e pi\u00f9 ampiamente i temi di cui si dibatte.<\/p>\n<p>9. &#8220;Internet \u00e8 la nuova sede per il discorso politico&#8221; Il giornalismo del XXI secolo deve fare in modo che il dibattito politico si trasferisca sempre di pi\u00f9 sulla rete cos\u00ec il pubblico potr\u00e0 partecipare direttamente ai discorsi politici e dire la sua.<\/p>\n<p>10. &#8220;Oggi libert\u00e0 di stampa significa libert\u00e0 d&#8217;opinione&#8221; I giornalisti non devono temere che la rete possa sminuire il loro compito di selezionare le notizie e informare. La vera dicotomia che invece internet realizza \u00e8 quella tra il buon e cattivo giornalismo.<\/p>\n<p>11. &#8220;Sempre di pi\u00f9: le informazioni non sono mai troppe&#8221; Sin dall&#8217;antichit\u00e0 l&#8217;umanit\u00e0 ha capito che pi\u00f9 informazioni si hanno pi\u00f9 \u00e8 grande la libert\u00e0. Internet \u00e8 il mezzo che pu\u00f2 pi\u00f9 di tutti pu\u00f2 allargare la nostra libert\u00e0.<\/p>\n<p>12. &#8220;La tradizione non \u00e8 un modello di business&#8221; Come dimostra gi\u00e0 la realt\u00e0 odierna \u00e8 possibile fare buon giornalismo su internet e guadagnare denaro. Non bisogna ignorare lo sviluppo tecnologico solo perch\u00e9 secondo alcuni distrugger\u00e0 le aziende giornalistiche, ma bisogna avere il coraggio di investire e ampliare la piattaforma multimediale.<\/p>\n<p>13. \u201cIl diritto d&#8217;autore diventa un dovere civico su Internet\u201d La rete deve rispettare il diritto d&#8217;autore, ma anche il sistema del copyright deve adattarsi ai nuovi modelli di distribuzione e non chiudersi nei meccanismi di approvvigionamento del passato.<\/p>\n<p>14. &#8220;Internet ha molte valute&#8221; Il modo pi\u00f9 tradizionale di finanziare i giornali online \u00e8 attraverso la pubblicit\u00e0. Altri modi per finanziare i prodotti giornalistici devono esseri testati.<\/p>\n<p>15. \u201cCio&#8217; che rimane sulla rete resta sulla rete\u201d Il giornalismo del XXI secolo non \u00e8 pi\u00f9 qualcosa di transitorio. Grazie alla rete tutto rimane nella memoria degli archivi e dei motori di ricerca e ci\u00f2 fa in modo che testi, suoni e immagini siano recuperabili e rappresentino fonti di storia contemporanea. Ci\u00f2 stimola a sviluppare un livello qualitativo sempre migliore.<\/p>\n<p>16. &#8220;La qualit\u00e0 resta la pi\u00f9 importante delle qualit\u00e0&#8221; Le richieste degli utenti sono sempre maggiori. Perch\u00e9 un utente resti fedele ad un particolare giornale online, quest&#8217;ultimo deve garantire qualit\u00e0 e soddisfare le richieste del lettore senza rinunciare ai propri principi.<\/p>\n<p>17. &#8220;Tutto per tutti&#8221; Internet ha dimostrato che l&#8217;utente giornalistico del XXI secolo \u00e8 esigente e nel caso di un dubbio su un articolo \u00e8 pronto a studiare la fonte per essere maggiormente informato. I giornalisti del XXI secolo che il lettore cerca non sono quelli che offrono solo risposte, ma quelli che sono disposti a comunicare e a indagare.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Via Penne digitali Diciasette dichiarazioni sul giornalismo di oggi,\u00a0raccolte in un Internet Manifesto, da\u00a0un gruppo di\u00a0autori\/blogger tedeschi, tutti esperti di \u201cNetz\u201d. Un documento interessante che Jaff Javis\u00a0si \u00e8 preso la\u00a0briga di tradurre in inglese, tramite Twitter. Internet Manifesto: How journalism works today. Seventeen declarations 1. &#8220;Internet \u00e8 diverso&#8221; Il nuovo mezzo di comunicazione \u00e8 molto &#8230; <a title=\"I blogger tedeschi lanciano un manifesto per il giornalismo on-line\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2009\/09\/10\/i-blogger-tedeschi-lanciano-un-manifesto-per-il-giornalismo-on-line\/\" aria-label=\"Per saperne di pi\u00f9 su I blogger tedeschi lanciano un manifesto per il giornalismo on-line\">Leggi tutto<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,6,30],"tags":[2157,160,2155],"class_list":["post-12821","post","type-post","status-publish","format-standard","hentry","category-blog","category-internet","category-media","tag-blog","tag-giornalismo","tag-internet"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/12821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=12821"}],"version-history":[{"count":1,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/12821\/revisions"}],"predecessor-version":[{"id":12822,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/12821\/revisions\/12822"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=12821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=12821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=12821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}