{"id":151,"date":"2004-05-29T08:32:30","date_gmt":"2004-05-29T06:32:30","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=151"},"modified":"2004-05-29T08:32:30","modified_gmt":"2004-05-29T06:32:30","slug":"108581235054315846","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2004\/05\/29\/108581235054315846\/","title":{"rendered":"108581235054315846"},"content":{"rendered":"<p><strong>Critical Mass<\/strong><br \/>\nMassa critica e&#8217; un nuovo modo di vivere nelle nostre citta&#8217; inquinate. Per costruire una nuova rivoluzione nel sistema dei transporti non hai null&#8217;altro da fare che prendere la bici e unirti a noi. Un sito per tutti quelli che credono che un&#8217;auto di meno in circolazione sia uno scopo comune.<\/p>\n<p>A Torino<br \/>\nogni primo giovedi&#8217; del mese partenza alle 21:00 davanti al Municipio, via Palazzo di Citta&#8217;<br \/>\ne<br \/>\nogni terzo sabato del mese partenza alle 21:00 davanti al Municipio, via Palazzo di Citta&#8217; <\/p>\n<p><a href=\"http:\/\/www.inventati.org\/criticalmass\/torino.htm\">http:\/\/www.inventati.org\/criticalmass\/torino.htm<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Critical Mass Massa critica e&#8217; un nuovo modo di vivere nelle nostre citta&#8217; inquinate. Per costruire una nuova rivoluzione nel sistema dei transporti non hai null&#8217;altro da fare che prendere la bici e unirti a noi. Un sito per tutti quelli che credono che un&#8217;auto di meno in circolazione sia uno scopo comune. A Torino &#8230; <a title=\"108581235054315846\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2004\/05\/29\/108581235054315846\/\" aria-label=\"Per saperne di pi\u00f9 su 108581235054315846\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[2160],"class_list":["post-151","post","type-post","status-publish","format-standard","hentry","tag-torino"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=151"}],"version-history":[{"count":0,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/151\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}