{"id":16424,"date":"2010-01-31T14:31:20","date_gmt":"2010-01-31T13:31:20","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=16424"},"modified":"2010-01-31T16:37:34","modified_gmt":"2010-01-31T15:37:34","slug":"previsioni-su-chi-si-salvera-nei-media-italiani-ed-europei","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2010\/01\/31\/previsioni-su-chi-si-salvera-nei-media-italiani-ed-europei\/","title":{"rendered":"Previsioni su chi si salvera nei media italiani ed europei ?"},"content":{"rendered":"<p><a href=\"http:\/\/www.lsdi.it\/2010\/01\/30\/industria-dell%E2%80%99-informazione-grandi-lavori-ancora-in-corso\/\">Via LSDI<\/a><\/p>\n<blockquote><p>Dovendo fare delle cifre \u2013 osserva Pierre Taillefer su <a href=\"http:\/\/mediawatch.afp.com\/?post\/2010\/01\/29\/Information-Industry-Summit-de-New-York-%3A-patience-les-restructurations-continuent\" target=\"_blank\">MediaWatch<\/a> \u2013 quelle che colpiscono di pi\u00f9 sono  sicuramente quelle fatte David Eun (vicepresidente YouTube, addetto agli  accordi strategici): in 60 giorni You Tube raccoglie tante immagini  quanto le 3 grandi catene americane ne hanno prodotte in 60 anni. Ogni  minuto vengono registrati 20 ore di video.<\/p>\n<p>Ma YouTube \u2013 aggiunge Taillefer \u2013 perde  soldi ed \u00e8 sempre alla ricerca di un modello economico in grado di  generare reddito. La conferenza si \u00e8 tenuta alla vigilia della presentazione dell\u2019 iPad  e tutti immaginavano ad alta voce le nuove frontiere che queste  lavagnette magiche dovrebbero aprire.<\/p>\n<p>La societ\u00e0 di analisi e studi <a href=\"http:\/\/www.outsellinc.com\/\">Outsell<\/a> ha messo le cose in prospettiva, sottolineando che i cambiamenti che si  sono accelerati nel 2009 non sono conclusi e ricordando che negli Stati  Uniti i giornali hanno visto ridursi del 20% i propri addetti in tre  anni.<\/p>\n<p>Per Outsell 12 imprese domineranno il mercato americano dei media e,  in generale, quello dei 900 milioni di anglofoni che ersistono al mondo.  E sono in ordine alfabetico: ABC, AP, BBC, Bloomberg, CBS, CNN, NBC,  New York Times, Newscorp, NPR, Thomson Reuters e Washington Post.<\/p><\/blockquote>\n<p>E in Europa e Italia chi si salver\u00e0 nel mercato dei media quando arriver\u00e0 lo tsunami definitivo ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Via LSDI Dovendo fare delle cifre \u2013 osserva Pierre Taillefer su MediaWatch \u2013 quelle che colpiscono di pi\u00f9 sono sicuramente quelle fatte David Eun (vicepresidente YouTube, addetto agli accordi strategici): in 60 giorni You Tube raccoglie tante immagini quanto le 3 grandi catene americane ne hanno prodotte in 60 anni. Ogni minuto vengono registrati 20 &#8230; <a title=\"Previsioni su chi si salvera nei media italiani ed europei ?\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2010\/01\/31\/previsioni-su-chi-si-salvera-nei-media-italiani-ed-europei\/\" aria-label=\"Per saperne di pi\u00f9 su Previsioni su chi si salvera nei media italiani ed europei ?\">Leggi tutto<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,30],"tags":[126,61,2168],"class_list":["post-16424","post","type-post","status-publish","format-standard","hentry","category-economia","category-media","tag-europa","tag-italia","tag-media"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/16424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=16424"}],"version-history":[{"count":3,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/16424\/revisions"}],"predecessor-version":[{"id":16426,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/16424\/revisions\/16426"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=16424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=16424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=16424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}