{"id":2087,"date":"2007-08-20T15:24:12","date_gmt":"2007-08-20T13:24:12","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/2007\/08\/20\/iphone-mini-test-drive\/"},"modified":"2007-08-20T15:24:12","modified_gmt":"2007-08-20T13:24:12","slug":"iphone-mini-test-drive","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2007\/08\/20\/iphone-mini-test-drive\/","title":{"rendered":"Iphone mini test drive"},"content":{"rendered":"<p>Via <a href=\"http:\/\/www.lastampa.it\/_web\/cmstp\/tmplrubriche\/tecnologia\/grubrica.asp?ID_blog=30&amp;ID_articolo=2945&amp;ID_sezione=38&amp;sezione=News\">Lastampa.it<\/a><\/p>\n<blockquote><p>In attesa del lancio dell\u2019Iphone sul territorio europeo sono apparsi i primi iphone acquistati negli Stati Uniti. Uno di questi \u00e8 atterrato a Hone in Valle d\u2019Aosta dove \u00e8 esposto nella <a href=\"http:\/\/www.allaboutapple.com\/speciali\/hone\" class=\"linkblu\" target=\"_blank\">mostra dedicata alla Apple<\/a> voluta fortemente dall\u2019infaticabile Walter Franceschi. \u00a0Ci sono per\u00f2 dei problemi telefonici, nel senso che l\u2019Iphone USA non funziona come telefono perch\u00e9 per ora \u00e8 inutilizzabile sul territorio europeo. Una limitazione grave, ma insormontabile allo stato attuale per la componente telefonica del device che \u00e8 di generazione 2.5.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Via Lastampa.it In attesa del lancio dell\u2019Iphone sul territorio europeo sono apparsi i primi iphone acquistati negli Stati Uniti. Uno di questi \u00e8 atterrato a Hone in Valle d\u2019Aosta dove \u00e8 esposto nella mostra dedicata alla Apple voluta fortemente dall\u2019infaticabile Walter Franceschi. \u00a0Ci sono per\u00f2 dei problemi telefonici, nel senso che l\u2019Iphone USA non funziona &#8230; <a title=\"Iphone mini test drive\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2007\/08\/20\/iphone-mini-test-drive\/\" aria-label=\"Per saperne di pi\u00f9 su Iphone mini test drive\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[54,56,2157,184,193,331,363],"class_list":["post-2087","post","type-post","status-publish","format-standard","hentry","tag-aosta","tag-apple","tag-blog","tag-iphone","tag-lastampa","tag-telefono","tag-web"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/2087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=2087"}],"version-history":[{"count":0,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/2087\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=2087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=2087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=2087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}