{"id":21765,"date":"2010-10-12T22:31:06","date_gmt":"2010-10-12T20:31:06","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=21765"},"modified":"2010-10-13T11:45:37","modified_gmt":"2010-10-13T09:45:37","slug":"strunz","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2010\/10\/12\/strunz\/","title":{"rendered":"Strunz"},"content":{"rendered":"<p><a href=\"http:\/\/www.pasteris.it\/blog\/wp-content\/uploads\/2010\/10\/strunz.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"strunz\" src=\"http:\/\/www.pasteris.it\/blog\/wp-content\/uploads\/2010\/10\/strunz.jpg\" alt=\"\" width=\"323\" height=\"311\" \/><\/a><br \/>\nRispolveriamo l&#8217;epiteto di germanico maccheronica lingua trapattoniana per qualificare il leader, si fa per dire, dei tifosi , si fa per dire, serbi, che hanno impedito lo svolgimento di Italia &#8211; Serbia allo stadio Luigi Ferraris di Genova.<\/p>\n<p>UPDATE:<a href=\"http:\/\/www.corriere.it\/sport\/10_ottobre_13\/arresti-genova-ivan-serbia_5cd210d4-d68e-11df-831d-00144f02aabc.shtml\"> il simpatico soggetto \u00e8 stato arrestato<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rispolveriamo l&#8217;epiteto di germanico maccheronica lingua trapattoniana per qualificare il leader, si fa per dire, dei tifosi , si fa per dire, serbi, che hanno impedito lo svolgimento di Italia &#8211; Serbia allo stadio Luigi Ferraris di Genova. UPDATE: il simpatico soggetto \u00e8 stato arrestato<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,32,9],"tags":[155,61,2156],"class_list":["post-21765","post","type-post","status-publish","format-standard","hentry","category-diritti","category-pensieri","category-sport","tag-genova","tag-italia","tag-sport"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/21765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=21765"}],"version-history":[{"count":4,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/21765\/revisions"}],"predecessor-version":[{"id":21769,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/21765\/revisions\/21769"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=21765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=21765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=21765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}