{"id":2463,"date":"2007-10-29T16:43:56","date_gmt":"2007-10-29T14:43:56","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/2007\/10\/29\/google-ci-vuole-puri\/"},"modified":"2007-10-29T16:43:56","modified_gmt":"2007-10-29T14:43:56","slug":"google-ci-vuole-puri","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2007\/10\/29\/google-ci-vuole-puri\/","title":{"rendered":"Google ci vuole puri"},"content":{"rendered":"<p>Da <a href=\"http:\/\/blog.webnews.it\/29\/10\/2007\/google-ci-vuole-puri\/\">Blog Webnews<\/a><\/p>\n<p>Non c\u2019\u00e8 pace nella blogosfera. Ora che si erano acquietate le discussioni su classifiche e correlate problematiche, a movimentare la situazione ci si \u00e8 messo di mezzo niente di meno che la grande G di <a href=\"http:\/\/www.google.com\/\">Google<\/a>.<\/p>\n<p>Nell\u2019ultima settimana \u00e8 stata completata la periodica messa a punto degli indicatori di Google, la tanto temuta <a href=\"http:\/\/en.wikipedia.org\/wiki\/Google_dance#Google_dance\">Google dance<\/a> il cui effetto pi\u00f9 visibile \u00e8 l\u2019aggiornamento del cosiddetto pagerank, il mitico numero che indica la maggiore o minore attendibilit\u00e0 di un sito o blog.<\/p>\n<p>Gli esiti della \u201cpulizia di autunno\u201d hanno avuto effetti pesanti per molti blogger piuttosto visibili con discese del pagerank fino a 2 o tre unit\u00e0. Qualche esempio: <a href=\"http:\/\/www.pandemia.info\/\">Pandemia<\/a> -2 (da 6 a 4); <a href=\"http:\/\/www.sw4n.net\/\">Sw4n<\/a> -3 (da 6 a 3); Robin Good nella reincarnazione <a href=\"http:\/\/www.masternewmedia.org\/\">MasterNewmedia<\/a> -3 (da 7 a 4), <a href=\"http:\/\/www.napolux.com\/\">Napolux<\/a> &#8211; 2 (da 5 a 3) solo per parlare di blog italiani . Negli Usa grandi siti <a href=\"http:\/\/searchengineland.com\/071024-093938.php\">hanno subito<\/a><a href=\"http:\/\/www.seomoz.org\/blog\/toolbar-pagerank-losses-for-hundreds-of-websites\"> analogo destino<\/a>.<\/p>\n<p>Qualcuno <a href=\"http:\/\/www.pasteris.it\/blog\/2007\/10\/28\/le-confessioni-di-un-bloggante-disperato\/\">l\u2019ha presa bene mettendola sul ridere<\/a>, <a href=\"http:\/\/www.masternewmedia.org\/it\/online_marketing\/Google-PageRank\/PageRank-svalutato-il-PR-ha-perso-tutto-il-suo-valore-20071026.htm\">qualcuno ci sta ragionando su<\/a>, qualcuno <a href=\"http:\/\/www.napolux.com\/2007\/10\/24\/google-vuole-la-guerra-e-che-guerra-sia\/\">\u00e8 decisamente incazzato<\/a>.<\/p>\n<p><a href=\"http:\/\/blog.webnews.it\/29\/10\/2007\/google-ci-vuole-puri\/\">Continua la lettura <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da Blog Webnews Non c\u2019\u00e8 pace nella blogosfera. Ora che si erano acquietate le discussioni su classifiche e correlate problematiche, a movimentare la situazione ci si \u00e8 messo di mezzo niente di meno che la grande G di Google. Nell\u2019ultima settimana \u00e8 stata completata la periodica messa a punto degli indicatori di Google, la tanto &#8230; <a title=\"Google ci vuole puri\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2007\/10\/29\/google-ci-vuole-puri\/\" aria-label=\"Per saperne di pi\u00f9 su Google ci vuole puri\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[2157,77,80,162,61,2168,511,363],"class_list":["post-2463","post","type-post","status-publish","format-standard","hentry","tag-blog","tag-blogger","tag-blogosfera","tag-google","tag-italia","tag-media","tag-pace","tag-web"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/2463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=2463"}],"version-history":[{"count":0,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/2463\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=2463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=2463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=2463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}