{"id":25737,"date":"2011-04-29T17:06:32","date_gmt":"2011-04-29T16:06:32","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=25737"},"modified":"2011-04-29T17:07:04","modified_gmt":"2011-04-29T16:07:04","slug":"giornalisti-ordine-ed-editori-5","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2011\/04\/29\/giornalisti-ordine-ed-editori-5\/","title":{"rendered":"Giornalisti, Ordine ed editori (5)"},"content":{"rendered":"<p><a href=\"http:\/\/www.lsdi.it\/2011\/04\/28\/giornalisti-pasteris-non-condivido\/\">Via LSDI<\/a><\/p>\n<blockquote><p>Il dibattito si sta animando su LSDI dopo l\u2019incontro svoltosi al  festival del Giornalismo di Perugia. E\u2019 cosa positiva che finalmente si affronti \u201ca cielo aperto\u201d le tematiche del precariato e della legalit\u00e0 del giornalismo italiano. Per quanto non personalmente non possa condividere diversi aspetti dell\u2019intervento del presidente ODG Iacopino occorre riconoscere che rispetto al recente passato si \u00e8 fatto un salto quantico in avanti.<\/p>\n<p>Nella precedente gestione non avremmo mai pensato di trovare un Presidente che prima si rende disponibile ad un incontro sapendo che si sarebbe trovato di fronte persone arrabbiate, insoddisfatte, stuprate intellettualmente, moralmente ed economicamente.<\/p>\n<p>Un Presidente che poi discute animatamente in rete, accettando la sfida  dell\u2019 Internet e della discussione. Forse questo non risolve molto nel concreto, ma \u00e8 gi\u00e0 un enorme passo avanti nel tentativo di avvicinare il mondo del giornalismo italiano a un necessario e traumatico cambiamento per lo status quo pregresso. La sfida non ha alternative: cambiare o morire con agonia veloce e molto dolorosa.<br \/>\nIn attesa di un intervento pi\u00f9 articolato sui temi del precariato e della legalit\u00e0 nel giornalismo, del rapporto fra giornalisti, editori e altri giornalisti, fra i giornalisti e la societ\u00e0 civile, rilancio la discussione citando il corpo di un articolo pubblicato sul <a href=\"http:\/\/www.ilfattoquotidiano.it\/2011\/04\/09\/i-precari-del-giornalismo-in-marcia\/103339\/\">sito del Fatto Quotidiano<\/a> il giorno dopo le manifestazioni dei precari in Italia.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Via LSDI Il dibattito si sta animando su LSDI dopo l\u2019incontro svoltosi al festival del Giornalismo di Perugia. E\u2019 cosa positiva che finalmente si affronti \u201ca cielo aperto\u201d le tematiche del precariato e della legalit\u00e0 del giornalismo italiano. Per quanto non personalmente non possa condividere diversi aspetti dell\u2019intervento del presidente ODG Iacopino occorre riconoscere che &#8230; <a title=\"Giornalisti, Ordine ed editori (5)\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2011\/04\/29\/giornalisti-ordine-ed-editori-5\/\" aria-label=\"Per saperne di pi\u00f9 su Giornalisti, Ordine ed editori (5)\">Leggi tutto<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,32],"tags":[140,1634,210,255,500],"class_list":["post-25737","post","type-post","status-publish","format-standard","hentry","category-media","category-pensieri","tag-fnsi","tag-legalita","tag-lsdi","tag-ordine-giornalisti","tag-precari"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/25737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=25737"}],"version-history":[{"count":2,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/25737\/revisions"}],"predecessor-version":[{"id":25739,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/25737\/revisions\/25739"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=25737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=25737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=25737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}