{"id":27001,"date":"2011-09-19T09:04:05","date_gmt":"2011-09-19T07:04:05","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=27001"},"modified":"2011-09-19T09:04:05","modified_gmt":"2011-09-19T07:04:05","slug":"nel-digitale-il-marketing-avanza-e-rompe-la-separazione-fra-statopubblicita-e-chiesainformazione","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2011\/09\/19\/nel-digitale-il-marketing-avanza-e-rompe-la-separazione-fra-statopubblicita-e-chiesainformazione\/","title":{"rendered":"Nel digitale il marketing avanza e rompe la separazione fra stato\/pubblicit\u00e0 e chiesa\/informazione"},"content":{"rendered":"<p><a href=\"http:\/\/www.lsdi.it\/2011\/09\/17\/giornalismo-digitale-il-marketing-avanza-e-rompe-la-separazione-fra-%E2%80%98%E2%80%99stato%E2%80%99%E2%80%99-pubblicita-e-%E2%80%98%E2%80%99chiesa%E2%80%99%E2%80%99-informazione-innovazioni-e-p\/\" target=\"_blank\">Via LSDI<\/a><\/p>\n<blockquote><p>Il paradosso \u00e8 che ora anche i promotori del marketing sono in possesso di strumenti per produrre e distribuire testi in maniera indipendente.  L\u2019ampliamento del numero di lettori una volta era affidato agli esperti di tiratura, ora \u00e8 assegnato a impiegati commerciali ed editoriali che sviluppano \u201cstrategie di crescita del pubblico\u201d individuando le forme migliori di copertura giornalistica. Quando decidono quali argomenti possano attrarre pi\u00f9 lettori, o lettori di fasce differenti, questo influisce sulla scelta dei blogger e sugli sforzi dello staff e dei collaboratori per trovare followers e fans.<\/p>\n<p>Forbes incoraggia inoltre i suoi inserzionisti pi\u00f9 grandi a produrre direttamente contenuti per il giornale e per il sito, come parte del loro acquisto di servizi pubblicitari. Alle aziende vengono forniti gli strumenti per pubblicare direttamente i contenuti (testi, video e immagini) sulla loro pagina nel sito.<\/p>\n<p>Avanza il marketing:  Etichettare il materiale come proveniente dagli inserzionisti aiuta a proteggere la testata dall\u2019 accusa di violare la divisione \u201cstato-chiesa\u201d, spiega DVorkin, aggiungendo che l\u2019 approccio di Forbes permette agli uomini del marketing di non essere confinati nel \u201cghetto\u201d dei redazionali scritti dai freelance.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Via LSDI Il paradosso \u00e8 che ora anche i promotori del marketing sono in possesso di strumenti per produrre e distribuire testi in maniera indipendente. L\u2019ampliamento del numero di lettori una volta era affidato agli esperti di tiratura, ora \u00e8 assegnato a impiegati commerciali ed editoriali che sviluppano \u201cstrategie di crescita del pubblico\u201d individuando le &#8230; <a title=\"Nel digitale il marketing avanza e rompe la separazione fra stato\/pubblicit\u00e0 e chiesa\/informazione\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2011\/09\/19\/nel-digitale-il-marketing-avanza-e-rompe-la-separazione-fra-statopubblicita-e-chiesainformazione\/\" aria-label=\"Per saperne di pi\u00f9 su Nel digitale il marketing avanza e rompe la separazione fra stato\/pubblicit\u00e0 e chiesa\/informazione\">Leggi tutto<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,32],"tags":[160,210],"class_list":["post-27001","post","type-post","status-publish","format-standard","hentry","category-media","category-pensieri","tag-giornalismo","tag-lsdi"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/27001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=27001"}],"version-history":[{"count":1,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/27001\/revisions"}],"predecessor-version":[{"id":27002,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/27001\/revisions\/27002"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=27001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=27001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=27001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}