{"id":27337,"date":"2011-10-25T23:16:48","date_gmt":"2011-10-25T21:16:48","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=27337"},"modified":"2011-10-25T23:16:48","modified_gmt":"2011-10-25T21:16:48","slug":"operazione-sassolini-uno","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2011\/10\/25\/operazione-sassolini-uno\/","title":{"rendered":"Operazione sassolini &#8211; uno"},"content":{"rendered":"<p>Oggi mi ha chiamato un &#8220;giornalista&#8221; piemontese che si \u00e8 costruito una carriera e rubando lo stipendio attraverso frequentazioni sindacali e ordinistiche. Dopo una sviolinata di un dieci minuti su quanto avevo ragione sul giornalismo digitale, su quanto ero bravo e forse bello mi ha chiesto se gli procuravo collaborazioni giornalistiche perch\u00e8 &#8220;sai il mestiere \u00e8 il mestiere&#8221;. Gli ho risposto sinteticamente che la mia stima nei suoi confronti era immutata rispetto al passato: pari a zero. Non so perch\u00e8 dopo brevi parole di commiato ha riattaccato.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi mi ha chiamato un &#8220;giornalista&#8221; piemontese che si \u00e8 costruito una carriera e rubando lo stipendio attraverso frequentazioni sindacali e ordinistiche. Dopo una sviolinata di un dieci minuti su quanto avevo ragione sul giornalismo digitale, su quanto ero bravo e forse bello mi ha chiesto se gli procuravo collaborazioni giornalistiche perch\u00e8 &#8220;sai il mestiere &#8230; <a title=\"Operazione sassolini &#8211; uno\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2011\/10\/25\/operazione-sassolini-uno\/\" aria-label=\"Per saperne di pi\u00f9 su Operazione sassolini &#8211; uno\">Leggi tutto<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,32],"tags":[161],"class_list":["post-27337","post","type-post","status-publish","format-standard","hentry","category-media","category-pensieri","tag-giornalisti"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/27337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=27337"}],"version-history":[{"count":2,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/27337\/revisions"}],"predecessor-version":[{"id":27339,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/27337\/revisions\/27339"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=27337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=27337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=27337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}