{"id":27418,"date":"2011-11-02T18:41:09","date_gmt":"2011-11-02T16:41:09","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=27418"},"modified":"2011-11-02T18:41:09","modified_gmt":"2011-11-02T16:41:09","slug":"ricordando-paolo-geymonat-lebook-costruire-web-company-di-successo-anche-in-italia-si-puo","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2011\/11\/02\/ricordando-paolo-geymonat-lebook-costruire-web-company-di-successo-anche-in-italia-si-puo\/","title":{"rendered":"Ricordando Paolo Geymonat: l&#8217;ebook Costruire web company di successo: anche in Italia si pu\u00f2"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" title=\"paolo geymonat\" src=\"http:\/\/farm4.static.flickr.com\/3569\/3408742751_4604a6ae5d.jpg\" alt=\"\" width=\"251\" height=\"188\" \/>A due anni <a href=\"http:\/\/www.pasteris.it\/blog\/2009\/09\/14\/obituary-paolo-geymonat\/\">dall&#8217;improvvisa scomparsa di Paolo Geymonat<\/a>, fondatore e e presidente di Bakeca,\u00a0insieme ad alcuni amici, abbiamo scritto un e-book curato da Sergio Chiarla per commemorarlo. Il libro \u00a0raccoglie attraverso le sue email lo spirito di un imprenditore, innovatore, filosofo ed essere umano di rara intelligenza, carisma, trascinante simpatia ed energia positiva.<\/p>\n<p>Il libro intitolato &#8216;Costruire web company di successo: anche in Italia si pu\u00f2!&#8217;,\u00a0\u00a0vuole essere di stimolo a tutti i giovani che stanno pensando di fare una startup. L&#8217;idea \u00e8 di offrire un orizzonte pi\u00f9 vicino ed accessibile della Silicon Valley.\u00a0Fare startup qui a casa nostra si pu\u00f2, la storia di Paolo Geymonat e Bakeca ne sono la testimonianza pi\u00f9 tangibile.<\/p>\n<p>&#8220;In molti scrivono sulla ricchezza e sul valore del sogno, ma \u00e8 difficile incontrare persone che sappiano realizzare in modo concreto i loro sogni.&#8221; scrive il curatore del libro, Sergio Chiarla, descrivendo la personalit\u00e0 di Paolo Geymonat. Sogno e concretezza, due facce della stessa medaglia, due ingredienti che ogni progetto dovrebbe avere per sfondare la porta del successo.<!--more--><\/p>\n<p>L&#8217;e-book verr\u00e0 reso disponibile sui principali distributori di e-book italiani e contestualmente sul portale <a href=\"http:\/\/www.retedeldono.it\">Rete del Dono<\/a> dove Bakeca ha aperto una pagina commemorativa e lanciato un\u2019iniziativa di raccolta fondi a favore di CasaOz Onlus, un\u2019associazione torinese che offre servizi di accoglienza e supporto alle famiglie\u00a0 con minori che vivono situazioni di malattia infantile.<\/p>\n<p>Il libro verr\u00e0 presentato il \u00a017 novembre alle 17, presso facolt\u00e0 di Economia e Commercio di Torino in un convegno dal titolo &#8216;Costruire web company di successo: anche in Italia si pu\u00f2!&#8217;. Partecipano: Alessandro Rivetti \u2013\u00a0Bakeca, Nader Sabbaghian \u2013\u00a0Bravosolution, Vito Lomele \u2013\u00a0Jobrapido,\u00a0 Gianluca Dettori \u2013\u00a0Vitaminic e Dpixel,\u00a0\u00a0 Nicola Canonico &#8211;\u00a0Easybit e Sosimple,\u00a0 Vittorio Pasteris \u2013\u00a0Giornalista e Blogger<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A due anni dall&#8217;improvvisa scomparsa di Paolo Geymonat, fondatore e e presidente di Bakeca,\u00a0insieme ad alcuni amici, abbiamo scritto un e-book curato da Sergio Chiarla per commemorarlo. Il libro \u00a0raccoglie attraverso le sue email lo spirito di un imprenditore, innovatore, filosofo ed essere umano di rara intelligenza, carisma, trascinante simpatia ed energia positiva. Il libro &#8230; <a title=\"Ricordando Paolo Geymonat: l&#8217;ebook Costruire web company di successo: anche in Italia si pu\u00f2\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2011\/11\/02\/ricordando-paolo-geymonat-lebook-costruire-web-company-di-successo-anche-in-italia-si-puo\/\" aria-label=\"Per saperne di pi\u00f9 su Ricordando Paolo Geymonat: l&#8217;ebook Costruire web company di successo: anche in Italia si pu\u00f2\">Leggi tutto<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[424],"tags":[1746,1555,1062],"class_list":["post-27418","post","type-post","status-publish","format-standard","hentry","category-personale","tag-akeka","tag-eboo","tag-geymonat"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/27418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=27418"}],"version-history":[{"count":2,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/27418\/revisions"}],"predecessor-version":[{"id":27421,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/27418\/revisions\/27421"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=27418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=27418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=27418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}