{"id":27970,"date":"2012-01-07T08:21:54","date_gmt":"2012-01-07T07:21:54","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=27970"},"modified":"2012-01-07T01:24:32","modified_gmt":"2012-01-07T00:24:32","slug":"lemigrazione-italiana","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2012\/01\/07\/lemigrazione-italiana\/","title":{"rendered":"L&#8217;emigrazione italiana"},"content":{"rendered":"<p><a href=\"http:\/\/it.wikipedia.org\/wiki\/Emigrazione_italiana\">Via wikipedia<\/a><\/p>\n<blockquote><p>L&#8217;Italia \u00e8 stata interessata al fenomeno dell&#8217;emigrazione soprattutto nei secoli XIX e XX. Il fenomeno ha riguardato dapprima il Settentrione (Piemonte, Veneto e Friuli in particolare) e, dopo il 1880, anche il Mezzogiorno. Dai porti del mediterraneo partirono molte navi con migliaia di italiani diretti in America per l&#8217;economia pi\u00f9 favorevole.<br \/>\nIndice<\/p>\n<p>Tra il 1861 e il 1985 sono state registrate pi\u00f9 di 29 milioni di partenze dall&#8217;Italia. Nell&#8217;arco di poco pi\u00f9 di un secolo un numero quasi equivalente all&#8217;ammontare della popolazione al momento dell&#8217;Unit\u00e0 d&#8217;Italia (25 milioni nel primo censimento italiano) si trasfer\u00ec in quasi tutti gli Stati del mondo occidentale e in parte del Nord Africa.<\/p>\n<p>Si tratt\u00f2 di un esodo che tocc\u00f2 tutte le regioni italiane. Tra il 1876 e il 1900 interess\u00f2 prevalentemente le regioni settentrionali, con tre regioni che fornirono da sole il 47% dell&#8217;intero contingente migratorio: il Veneto (17,9%), il Friuli-Venezia Giulia (16,1%) ed il Piemonte (12,5%). Nei due decenni successivi il primato migratorio pass\u00f2 alle regioni meridionali, con quasi tre milioni di persone emigrate soltanto da Calabria, Campania, Puglia e Sicilia, e quasi nove milioni da tutta Italia.<\/p>\n<p>Si pu\u00f2 distinguere l&#8217;emigrazione italiana in due grandi periodi: quello della grande emigrazione tra la fine del XIX secolo e gli anni trenta del XX secolo (dove fu preponderante l&#8217;emigrazione americana) e quello dell&#8217;emigrazione europea, che ha avuto inizio a partire dagli anni cinquanta.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Via wikipedia L&#8217;Italia \u00e8 stata interessata al fenomeno dell&#8217;emigrazione soprattutto nei secoli XIX e XX. Il fenomeno ha riguardato dapprima il Settentrione (Piemonte, Veneto e Friuli in particolare) e, dopo il 1880, anche il Mezzogiorno. Dai porti del mediterraneo partirono molte navi con migliaia di italiani diretti in America per l&#8217;economia pi\u00f9 favorevole. Indice Tra &#8230; <a title=\"L&#8217;emigrazione italiana\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2012\/01\/07\/lemigrazione-italiana\/\" aria-label=\"Per saperne di pi\u00f9 su L&#8217;emigrazione italiana\">Leggi tutto<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1806,61],"class_list":["post-27970","post","type-post","status-publish","format-standard","hentry","category-politica","tag-emigrazione","tag-italia"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/27970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=27970"}],"version-history":[{"count":2,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/27970\/revisions"}],"predecessor-version":[{"id":27972,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/27970\/revisions\/27972"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=27970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=27970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=27970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}