{"id":3318,"date":"2008-04-01T12:51:00","date_gmt":"2008-04-01T10:51:00","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/2008\/04\/01\/federico-barbarossa-ospite-al-palio-di-villareggia\/"},"modified":"2008-04-02T04:59:19","modified_gmt":"2008-04-02T02:59:19","slug":"federico-barbarossa-ospite-al-palio-di-villareggia","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2008\/04\/01\/federico-barbarossa-ospite-al-palio-di-villareggia\/","title":{"rendered":"Federico Barbarossa &#8220;ospite&#8221; al Palio di Villareggia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm2.static.flickr.com\/1425\/560595778_4e60dc76ed.jpg?v=0\" align=\"right\" height=\"245\" width=\"368\" \/>Il Comitato <a href=\"http:\/\/www.paliodivillareggia.it\/\">Palio di Villareggia<\/a> comunica  che la Terza Edizione del Palio dei Cantoni si svolger\u00e0 dal 7 al 21 giugno 2008.Si tratter\u00e0 di 2  settimane piene di eventi e gare,  ricco di novit\u00e0 e molto divertente.<\/p>\n<p>La &#8220;novit\u00e0&#8221; che da quest\u2019anno accompagner\u00e0 il Palio di Villareggia consiste nella ripresa della famosa tesi di laurea di Maria Gianetto (madrina del bloggante che prima o poi trover\u00e0 il tempo di editare e aggiornare il lavoro n.d.b.) che riporta la notizia che Federico Barbarossa fu a Villareggia nell\u2019autunno del 1157. Dovendo il Barbarossa recarsi ad una battuta di caccia, egli lasci\u00f2 la giovane moglie Beatrice di Borgogna presso i Biandrate, proprio qui a Villareggia, nel piccolo borgo presso la Dora Baltea &#8230; Il resto al Palio!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comitato Palio di Villareggia comunica che la Terza Edizione del Palio dei Cantoni si svolger\u00e0 dal 7 al 21 giugno 2008.Si tratter\u00e0 di 2 settimane piene di eventi e gare, ricco di novit\u00e0 e molto divertente. La &#8220;novit\u00e0&#8221; che da quest\u2019anno accompagner\u00e0 il Palio di Villareggia consiste nella ripresa della famosa tesi di laurea &#8230; <a title=\"Federico Barbarossa &#8220;ospite&#8221; al Palio di Villareggia\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2008\/04\/01\/federico-barbarossa-ospite-al-palio-di-villareggia\/\" aria-label=\"Per saperne di pi\u00f9 su Federico Barbarossa &#8220;ospite&#8221; al Palio di Villareggia\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[2157,138,426,561,357],"class_list":["post-3318","post","type-post","status-publish","format-standard","hentry","tag-blog","tag-flickr","tag-lavoro","tag-tempo","tag-villareggia"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/3318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=3318"}],"version-history":[{"count":0,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/3318\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=3318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=3318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=3318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}