{"id":33314,"date":"2014-12-26T14:13:10","date_gmt":"2014-12-26T12:13:10","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=33314"},"modified":"2014-12-26T14:14:01","modified_gmt":"2014-12-26T12:14:01","slug":"perche-sto-con-papa-francesco-e-mi-fanno-ridere-mirabolanti-rivoluzionari-del-cambiamento-per-modo-di-dire","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2014\/12\/26\/perche-sto-con-papa-francesco-e-mi-fanno-ridere-mirabolanti-rivoluzionari-del-cambiamento-per-modo-di-dire\/","title":{"rendered":"Perche sto con Papa Francesco e mi fanno ridere i mirabolanti rivoluzionari del cambiamento per modo di dire"},"content":{"rendered":"<p><a href=\"http:\/\/www.ilfattoquotidiano.it\/2014\/12\/24\/papa-francesco-perche-stiamo-bergoglio\/1295637\/\" target=\"_blank\">Antonio Padellaro sul Fatto Quotidiano<\/a><\/p>\n<blockquote><p>Non occorre essere credenti per avere un senso religioso della vita e per saper distinguere ci\u00f2 che \u00e8 bene da ci\u00f2 che non lo \u00e8. Per esempio, basta assistere a una messa domenicale e anche chi ritiene che l\u2019ostia consacrata sia soltanto un frammento di pane azzimo non potr\u00e0 non riflettere sul raccoglimento delle persone che si avvicinano all\u2019altare; su quel preciso momento in cui in esse sembra dileguarsi ogni fatica, ogni dispiacere del mondo quotidiano. Perfino l\u2019ateo pi\u00f9 incallito non potr\u00e0 non riconoscere che quei fedeli abbiano trovato un benessere interiore che, magari per un solo istante, li render\u00e0 per cos\u00ec dire migliori.<\/p>\n<p>L\u00ec certamente batte il cuore di una comunit\u00e0 unita nella fede, l\u00ec c\u2019\u00e8 la Chiesa che aiuta e che consola. Ma ne esiste un\u2019altra di chiesa, purtroppo, ed \u00e8 sufficiente leggere le<a href=\"http:\/\/www.ilfattoquotidiano.it\/2014\/12\/22\/papa-francesco-15-malattie-curiali-perdonateci-per-gli-scandali\/1289390\/\" target=\"_blank\"> quindici malattie della Curia romana secondo papa Bergoglio<\/a> per comprendere come la descrizione puntuale di quei mali non riguardi soltanto le porpore vaticane smarrite nei propri vizi e affette da \u201cAlzheimer spirituale\u201d. Perch\u00e9 \u00e8 cos\u00ec che Francesco continua a parlarci della battaglia finale tra forze opposte che convivono sotto la stessa croce. Senza scomodare gli angeli e i demoni di Dan Brown, non \u00e8 uno scontro di potere: \u00e8 in gioco l\u2019affermazione o la sconfitta dei valori universali di pace, di uguaglianza, di tolleranza e di giustizia sociale, dentro ma anche oltre i confini della dottrina cattolica.<\/p>\n<p>Solo che, sembra avvertirci Bergoglio, la coesistenza (tante volte descritta su queste pagine da <a href=\"http:\/\/www.ilfattoquotidiano.it\/blog\/mpoliti\/\" target=\"_blank\">Marco Politi<\/a>) tra la Chiesa della carit\u00e0 e la chiesa del carrierismo, tra quella altezzosamente dottrinaria e quella che preferisce stare tra la gente, \u00e8 sempre pi\u00f9 difficile e impone ormai una scelta di campo. Che non riguarda solo i cattolici, ma anche il mondo laico che non pu\u00f2 fare finta di non vedere. Perch\u00e9, se perde Francesco, con lui si consumer\u00e0 una speranza formidabile di dialogo e di rinnovamento, mentre la restaurazione svuoter\u00e0 di nuovo piazza San Pietro e il cuore di milioni di persone. Per questo Francesco combatte per tutti gli uomini di buona volont\u00e0. Per questo bisogna stargli accanto.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Antonio Padellaro sul Fatto Quotidiano Non occorre essere credenti per avere un senso religioso della vita e per saper distinguere ci\u00f2 che \u00e8 bene da ci\u00f2 che non lo \u00e8. Per esempio, basta assistere a una messa domenicale e anche chi ritiene che l\u2019ostia consacrata sia soltanto un frammento di pane azzimo non potr\u00e0 non &#8230; <a title=\"Perche sto con Papa Francesco e mi fanno ridere i mirabolanti rivoluzionari del cambiamento per modo di dire\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2014\/12\/26\/perche-sto-con-papa-francesco-e-mi-fanno-ridere-mirabolanti-rivoluzionari-del-cambiamento-per-modo-di-dire\/\" aria-label=\"Per saperne di pi\u00f9 su Perche sto con Papa Francesco e mi fanno ridere i mirabolanti rivoluzionari del cambiamento per modo di dire\">Leggi tutto<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,32,424],"tags":[2133,2059],"class_list":["post-33314","post","type-post","status-publish","format-standard","hentry","category-mondo","category-pensieri","category-personale","tag-cambiamento","tag-papa-francesco"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/33314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=33314"}],"version-history":[{"count":1,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/33314\/revisions"}],"predecessor-version":[{"id":33315,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/33314\/revisions\/33315"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=33314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=33314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=33314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}