{"id":34523,"date":"2018-08-10T08:16:52","date_gmt":"2018-08-10T06:16:52","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=34523"},"modified":"2018-08-09T08:12:47","modified_gmt":"2018-08-09T06:12:47","slug":"cuore-di-cobra-riccardo-ricco-riccardo-ricco-presenta-il-suo-libro-e-spiega-solo-col-doping-non-vinci-senza-doping-non-vinci","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2018\/08\/10\/cuore-di-cobra-riccardo-ricco-riccardo-ricco-presenta-il-suo-libro-e-spiega-solo-col-doping-non-vinci-senza-doping-non-vinci\/","title":{"rendered":"Cuore di Cobra. Riccardo Ricc\u00f2 : Riccardo Ricc\u00f2 presenta il suo libro e spiega: \u201cSolo col doping non vinci, senza doping non vinci\u201c"},"content":{"rendered":"<p><a href=\"https:\/\/it.wikipedia.org\/wiki\/Riccardo_Ricc%C3%B2\">Riccardo Ricc\u00f2<\/a> <a href=\"http:\/\/www.edizpiemme.it\/libri\/cuore-di-cobra\">racconta la sua storia e quella del mondo del ciclismo<\/a><\/p>\n<blockquote><p>Pensate che i grandi che hanno scritto la storia del ciclismo e che sono stati coinvolti a vario titolo in scandali doping fossero diversi dal resto del gruppo? Che fossero migliori o peggiori degli altri? Credete che, prima di loro, di quegli anni, la situazione fosse diversa, o che possa essere cambiata negli anni successivi? Pensate che si possano fare 200 chilometri al giorno per tre settimane tra sole, gelo, pioggia, vento e neve solo a pane e acqua? Pensate che si possa davvero vincere cos\u00ec, o che ci sarebbe mai una tv disposta ad aspettarti al traguardo in diretta per 7, 8, 10 ore, cio\u00e8 il tempo fisiologico per un tappone di montagna con 4.500 metri di dislivello? E, una volta arrivati, essere pronti gi\u00e0 il mattino dopo a rifare la stessa cosa? Vi siete mai chiesti perch\u00e9 ogni tappa di un grande giro arriva d&#8217;abitudine tra le 17 e le 17,30? Perch\u00e9 in quell&#8217;orario si deve arrivare, se no &#8220;non ci stiamo con il palinsesto, e addio a pubblicit\u00e0 e spot.&#8221;<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Riccardo Ricc\u00f2 racconta la sua storia e quella del mondo del ciclismo Pensate che i grandi che hanno scritto la storia del ciclismo e che sono stati coinvolti a vario titolo in scandali doping fossero diversi dal resto del gruppo? Che fossero migliori o peggiori degli altri? Credete che, prima di loro, di quegli anni, &#8230; <a title=\"Cuore di Cobra. Riccardo Ricc\u00f2 : Riccardo Ricc\u00f2 presenta il suo libro e spiega: \u201cSolo col doping non vinci, senza doping non vinci\u201c\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2018\/08\/10\/cuore-di-cobra-riccardo-ricco-riccardo-ricco-presenta-il-suo-libro-e-spiega-solo-col-doping-non-vinci-senza-doping-non-vinci\/\" aria-label=\"Per saperne di pi\u00f9 su Cuore di Cobra. Riccardo Ricc\u00f2 : Riccardo Ricc\u00f2 presenta il suo libro e spiega: \u201cSolo col doping non vinci, senza doping non vinci\u201c\">Leggi tutto<\/a><\/p>\n","protected":false},"author":3,"featured_media":34524,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[424],"tags":[2883,1272,2440,2884],"class_list":["post-34523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-personale","tag-cobra","tag-cuore","tag-riccardo","tag-ricco"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/34523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=34523"}],"version-history":[{"count":1,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/34523\/revisions"}],"predecessor-version":[{"id":34525,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/34523\/revisions\/34525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media\/34524"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=34523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=34523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=34523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}