{"id":34920,"date":"2019-05-02T18:26:45","date_gmt":"2019-05-02T16:26:45","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=34920"},"modified":"2019-05-02T18:35:09","modified_gmt":"2019-05-02T16:35:09","slug":"le-riviste-predatorie-per-far-carriera-furbescamente-nelluniversita","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2019\/05\/02\/le-riviste-predatorie-per-far-carriera-furbescamente-nelluniversita\/","title":{"rendered":"Le riviste predatorie per far carriera furbescamente nell&#8217;universit\u00e0"},"content":{"rendered":"<p><a href=\"https:\/\/www.ilmessaggero.it\/index.php?p=item&amp;id=4451719&amp;sez=italia&amp;start=0\">Via il Messaggero<\/a><\/p>\n<blockquote><p>Sono stati spesi quasi 2,5 milioni di euro per vedere pubblicate ricerche scientifiche che probabilmente, senza spendere un euro, non sarebbero andate da nessuna parte. <a href=\"https:\/\/web.archive.org\/web\/20161202192038\/https:\/\/scholarlyoa.com\/individual-journals\/\">Pubblicazioni praticamente fasulle<\/a>, comprate, utili solo ad arricchire curriculum, indispensabili per\u00f2 per far carriera. Cos\u00ec migliaia di ricercatori universitari hanno tentato la scalata alla carriera accademica. Alcuni hanno cercato la scorciatoia, altri ci sono letteralmente cascati, pensando di pagare per una valutazione in piena regola. Accade in Italia, dove per accedere ai concorsi necessari alla carriera di professore ordinario bisogna aver acquisito l\u2019Asn, l\u2019Abilitazione scientifica nazionale. E per averla \u00e8 necessario presentare nel proprio curriculum le pubblicazioni ottenute durante gli studi e la preparazione. Se le pubblicazioni non ci sono, l\u2019abilitazione non arriva.<\/p>\n<p>C\u2019\u00e8 chi le ottiene con il proprio studio vantando ricerche di interesse notevole, chi si affida a gruppi di ricerca trainati da docenti dal nome importante e chi invece apre il portafogli per vedere il proprio nome pubblicato su pseudo riviste scientifiche, meglio note come \u201c<a href=\"https:\/\/it.wikipedia.org\/wiki\/Pubblicazione_predatoria\">riviste predatorie<\/a>\u201d, che pubblicano tutto quel che arriva. Dietro compenso, ovviamente, e senza attivare i dovuti controlli: il \u201cpeer review\u201d che un editore scientifico dovrebbe garantire. Ad aprire questo vaso di Pandora, che ora scuote il mondo accademico, <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0048733318300945\">\u00e8 uno studio portato avanti da Mauro Sylos Labini, un ricercatore del dipartimento di Scienze politiche dell\u2019Universit\u00e0 di Pisa, da Manuel Bagues dell\u2019Universit\u00e0 di Warwick in Inghilterra e da Natalia Zinovyeva dell\u2019Universit\u00e0 di Aalto in Finlandia.<\/a><\/p>\n<p>I tre ricercatori hanno passato al setaccio i curriculum di 46mila tra ricercatori e professori che comparivano nelle candidature della prima edizione dell\u2019Abilitazione Scientifica Nazionale dell\u2019anno 2012-13. Che cosa emerge dalla ricerca? Circa il 5% dei partecipanti all\u2019abilitazione scientifica nazionale ha utilizzato le riviste predatorie almeno una volta. Vale a dire oltre 2000 ricercatori universitari. \u00abUna stima conservativa basata sulla nostra indagine &#8211; spiega Mauro Sylos Labini &#8211; suggerisce che per pubblicare circa seimila articoli, i ricercatori del campione hanno speso pi\u00f9 di due milioni e mezzo di dollari.<\/p>\n<p>Con una media di 440 dollari ad articolo, circa 400 euro. Parte di questa cifra esce direttamente dalle tasche dei ricercatori, ma un\u2019altra parte proviene dai loro fondi di ricerca pubblici, e si tratta comunque di una stima che non tiene conto delle spese per la partecipazione a conferenze \u201cpredatorie\u201d, spesso associate a queste pubblicazioni\u201d. Un pacchetto completo, quindi, composto da pubblicazioni e convegni. Finalizzato a veder innalzare il punteggio utile per ottenere la certificazione necessaria a far carriera nell\u2019Universit\u00e0.<\/p>\n<p>Tra i 2mila docenti ci sono anche i ricercatori che non sapevano di incappare in una scorciatoia poco professionale. I settori scientifici maggiormente interessati da questo escamotage sono Economia aziendale, Organizzazione e Finanza aziendale. Sono questi infatti i campi in cui sono state riscontrate maggiormente le pubblicazioni a pagamento. Ma, tenendo presente il tariffario delle riviste predatorie, lo spreco di risorse sembra essere maggiore per le pubblicazioni nel campo della Medicina dove una pubblicazione pu\u00f2 arrivare a costare anche 2.500 dollari, circa 2200 euro. Pi\u00f9 pubblicazioni si hanno, maggiore \u00e8 la possibilit\u00e0 di veder aumentare il proprio h\u2013index, il punteggio con cui si giudica l\u2019attivit\u00e0 di un ricercatore. Il fenomeno delle pubblicazioni a pagamento \u00e8 ben noto all\u2019estero tanto che esistono vere e proprie liste nere con i nomi delle riviste. Una delle pi\u00f9 famose \u00e8 quella messa a punto da un bibliotecario dell\u2019Universit\u00e0 del Colorado, Jeffrey Beall. Un esempio celebre \u00e8 la pubblicazione della trama della puntata di Star Trek \u201cVojager\u201d: un ricercatore dal nome fittizio Zimmerman, volendo svelare l\u2019inganno, riusc\u00ec a farsi pubblicare la ricerca, passandola per buona, dall\u2019American Research Journal of Biosciences che gli chiese 749 euro. Alla fine ne bastarono 50.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Via il Messaggero Sono stati spesi quasi 2,5 milioni di euro per vedere pubblicate ricerche scientifiche che probabilmente, senza spendere un euro, non sarebbero andate da nessuna parte. Pubblicazioni praticamente fasulle, comprate, utili solo ad arricchire curriculum, indispensabili per\u00f2 per far carriera. Cos\u00ec migliaia di ricercatori universitari hanno tentato la scalata alla carriera accademica. Alcuni &#8230; <a title=\"Le riviste predatorie per far carriera furbescamente nell&#8217;universit\u00e0\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2019\/05\/02\/le-riviste-predatorie-per-far-carriera-furbescamente-nelluniversita\/\" aria-label=\"Per saperne di pi\u00f9 su Le riviste predatorie per far carriera furbescamente nell&#8217;universit\u00e0\">Leggi tutto<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,424],"tags":[],"class_list":["post-34920","post","type-post","status-publish","format-standard","hentry","category-politica","category-personale"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/34920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=34920"}],"version-history":[{"count":2,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/34920\/revisions"}],"predecessor-version":[{"id":34926,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/34920\/revisions\/34926"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=34920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=34920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=34920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}