{"id":35243,"date":"2021-01-14T02:42:21","date_gmt":"2021-01-14T00:42:21","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=35243"},"modified":"2021-01-14T02:42:21","modified_gmt":"2021-01-14T00:42:21","slug":"dagospia-e-leutanasia-dellinpgi","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2021\/01\/14\/dagospia-e-leutanasia-dellinpgi\/","title":{"rendered":"Dagospia e l&#8217;eutanasia dell&#8217;INPGI"},"content":{"rendered":"<p>Via Dagospia<\/p>\n<blockquote><p>Niente e nessuno potr\u00e0 salvare l\u2019Inpgi, l\u2019ente di previdenza dei giornalisti privatizzato nel lontano \u201994, dal dissesto definitivo. Solo un ritorno sotto le ali dell\u2019Inps, come fecero i dirigenti d\u2019azienda nel 2003 quando i conti del loro ente privatizzato, l\u2019Inpdai, mostravano un deficit di 600 milioni, potr\u00e0 garantire la sostenibilit\u00e0 nel lungo periodo delle pensioni dei giornalisti.<!--more--><\/p>\n<p>Tutto il resto, cio\u00e8 la pervicacia con cui i vertici dell\u2019Inpgi, ma anche il sindacato e l\u2019Ordine professionale come vedremo, continuano a propugnare la via privata e autonoma dell\u2019ente, \u00e8 mera retorica, propaganda spicciola che fa a pugni con la realt\u00e0.<\/p>\n<p>Nessuna auto-riforma (l\u2019ultima del 2017) e tanto meno il piano di tagli e aumento dei contributi, emerso da un documento riservato reso pubblico (meritoriamente) da alcuni membri dissenzienti del Cda dell\u2019Inpgi, potr\u00e0 garantire che l\u2019Inpgi sopravviva cos\u00ec com\u2019\u00e8.<\/p>\n<p>Il piano mette insieme una serie di piccole misure che valgono un risparmio di alcune decine di milioni, una goccia nel mare del dissesto.<\/p>\n<p>I conti dell\u2019istituto sono fuori controllo da anni. Il bilancio del 2020 mostra un buco della sola gestione previdenziale di circa 200 milioni. Ogni anno il buco tende inevitabilmente a peggiorare.<\/p>\n<p>Sempre meno contributi dalla fuoriuscita massiccia dei giornalisti dalle aziende e sempre pi\u00f9 pensioni da pagare. Ormai il rapporto tra giornalisti e pensionati \u00e8 insostenibile. A fronte di 15mila attivi, ci sono ormai quasi 10mila pensionati. Il rapporto che garantisce la sostenibilit\u00e0 sarebbe di almeno 3 a 1 se non 4 a 1. Qui siamo a 1,5.<\/p>\n<p>La prima perdita \u00e8 antica. Gi\u00e0 nel 2011 per la prima volta il rapporto tra entrate e uscite previdenziali and\u00f2 in rosso. Da allora il buco si \u00e8 fatto esponenziale. Oggi \u00e8 di 200 milioni, e si allargher\u00e0 ulteriormente dato che il Governo, lo stesso che dice di voler affrontare il collasso dell\u2019Inpgi, ha nel frattempo deliberato la nuova tornata di pre-pensionamenti, che scaricher\u00e0 sull\u2019Inpgi un nuovo deficit. Come si vede il disastro non solo era annunciato da anni, ma \u00e8 nelle cose.<\/p>\n<p>Ebbene la carta nel mazzo del presidente dell\u2019Inpgi Marina Macelloni, \u00e8 stata negli ultimi 2 anni quella dell\u2019allargamento della base contributiva. Tutti quei dipendenti pubblici e privati che fanno i comunicatori passerebbero dall\u2019Inps all\u2019Inpgi. Problema risolto.<\/p>\n<p>Peccato che i cosiddetti comunicatori abbiano appreso solo dai giornali della mirabolante idea della presidente dell\u2019Inpgi. E non a caso hanno parlato di deportazione e di sacrificio. Perch\u00e9 mai i comunicatori dovrebbero abbandonare il lido pubblico dell\u2019Inps per sostenere i costi di un ente previdenziale privato?<\/p>\n<p>Forse se si fosse trattato con la rappresentanza dei comunicatori, anzich\u00e9 annunciarlo in modo arrogante e spregiudicato sui giornali, spiegando loro che l\u2019Inpgi fino a tutto il 2017, garantiva aliquote di rendimento superiori all\u2019Inps, forse dico forse, la loro reazione di forte contrariet\u00e0 non sarebbe stata cos\u00ec esplicita. Un autogol su cui l\u2019Inpgi \u00e8 andata a sbattere.<\/p>\n<p>Sono innumerevoli e ben distribuite. I vertici dell\u2019Istituto succedutesi nell\u2019ultimo decennio hanno tirato a campare, traccheggiando a fronte di una crisi strutturale dell\u2019editoria che doveva mettere in guardia gi\u00e0 nel 2011 dall\u2019insostenibilit\u00e0 prospettica dei conti.<\/p>\n<p>Il venir meno dei contributi per l\u2019emorragia di posti di lavoro causa la crisi dell\u2019editoria e contemporaneamente l\u2019aumento esponenziale dei pensionati allargava ogni anno la forbice tra costi e ricavi.<\/p>\n<p>I ministeri vigilanti hanno avuto il ruolo del convitato di pietra. Mai un intervento di messa in guardia, nonostante la Corte dei Conti gi\u00e0 nel 2014 lanciava l\u2019allarme sul declino inevitabile dell\u2019Inpgi. Il sindacato e l\u2019Ordine muti, anzi tuttora a spalleggiare le proposte mirabolanti di cura dei vertici. Ora l\u2019Ordine ha tirato fuori il coniglio dal cilindro. Chiedere la garanzia pubblica delle pensioni Inpgi.<\/p>\n<p>Risibile. Se sei un ente privatizzato, non puoi chiedere aiuti pubblici allo Stato se poi mantieni la tua autonomia. O sei pubblico a tutti gli effetti o rimani privato, accollandoti tutte le responsabilit\u00e0 Il tutto in nome di una presunta autonomia come valore fondante della professione. L\u2019autonomia i giornalisti se la devono guadagnare sul campo della professione, non su quello della gestione finanziaria del loro ente previdenziale.<\/p>\n<p>Se vuoi continuare a rimanere privato devi mettere in conto di dover portare i libri in Tribunale, se i conti non tornano e sei privatizzato, devi accettare l\u2019idea del fallimento come qualsiasi ente economico privato.<\/p>\n<p>Imputare del dissesto i vertici dell\u2019istituto anche questo \u00e8 pura retorica. La crisi del mercato del lavoro \u00e8 oggettiva. I pre-pensionamenti, alcuni molti facili permessi dallo Stato con la causale della crisi prospettica, e avvallati dal sindacato, hanno consentito ad aziende in utile (leggi Repubblica ad esempio) di scaricare i costi aziendali sull\u2019Inpgi. E la contrazione dei rapporti di lavoro ha fatto il resto.<\/p>\n<p>Certo la miopia c\u2019\u00e8 stata e profonda. L\u2019istituto \u00e8 stato a guardare, non ha preso di petto la situazione gi\u00e0 dieci anni fa, quando il patrimonio non era eroso dalle perdite, e quando si poteva imboccare pi\u00f9 facilmente il rientro nell\u2019alveo pubblico da condizioni di relativa forza. Oggi si va a chiedere il soccorso pubblico con il cappello in mano. Le due riforme del decennio (2011 e 2017) non hanno invertito la situazione. Perch\u00e9 di fatto non \u00e8 sanabile.<\/p>\n<p>Ogni anno, pur con le riforme, il buco previdenziale aumenta di una cinquantina di milioni. Prova ne \u00e8 che da solo l\u2019Inpgi non pu\u00f2 farcela.<\/p>\n<p>Per colmare il buco occorrerebbe un taglio pesantissimo delle pensioni e\/o un aumento intollerabile dei contributi Per colmare il disavanzo attuale di 200 milioni, si dovrebbero tagliare le pensioni del 20-30% e insieme aumentare i contributi di entit\u00e0 analoga. Un bagno di sangue intollerabile e probabilmente anti costituzionale soprattutto sui trattamenti in essere, ma anche sui contributi dato che ora sono allineati al regime Inps.<\/p>\n<p>A proposito di contributi e della responsabilit\u00e0 in capo ai vertici dell\u2019ente.<\/p>\n<p>Per decenni le aziende editoriali hanno versato contributi pi\u00f9 bassi di 2-3 punti percentuali rispetto all\u2019Inps. Un regalo agli editori, sanato solo negli ultimi anni.<\/p>\n<p>C\u2019\u00e8 un tema spinoso che nessuno ha mai affrontato e che non salver\u00e0 l\u2019Inpgi, ma chiama in causa le gestioni di chi ha governato l\u2019Istituto negli ultimi anni. L\u2019Inpgi ha una mole di contribuiti non riscossi enorme. Sono i contributi degli editori, dato che i giornalisti vedono il loro contributo (il 9% pi\u00f9 un 1% aggiuntivo per retribuzioni sopra i 44 mila euro) trattenuto direttamente in busta paga. Ebbene il monte contributi non riscossi ammonta a ben 277 milioni di euro. Un livello che si trascina inalterato da anni. Nel 2011 il monte contributi evasi o meglio in sofferenza era di 274 milioni di euro.<\/p>\n<p>Come si vede nulla \u00e8 successo. L\u2019ente si trascina da un decennio una montagna di contributi non pagati dalle aziende senza fare quasi alcunch\u00e8. I tassi di recupero come ha rilevato la Corte dei Conti sono risibili. Pochi milioni l\u2019anno. E cos\u00ec ogni anno l\u2019ente deve svalutare i crediti in sofferenza di decine di milioni. C\u2019\u00e8 un fondo svalutazione di un centinaio di milioni nel bilancio dell\u2019Inpgi tuttora. Ebbene la Corte dei Conti nella relazione del 2017 metteva in luce la scarsissima capacit\u00e0 di recupero da parte dell\u2019Inpgi e suggeriva di passare a misure pi\u00f9 drastiche come la riscossione coattiva. Insomma se gli editori non pagano si potrebbero pignorare i loro beni. E\u2019 stato fatto?<\/p>\n<p>Vero \u00e8 che di quei 277 milioni, una cinquantina sono ritardi di incassi da un anno con l\u2019altro che quindi vengono poi riscossi e un\u2019altra cinquantina sono contributi non pagati da aziende fallite. Restano in ogni caso almeno 170 milioni di sofferenze da recuperare. Perch\u00e9 non assumere giovani laureati disoccupati come ispettori, con magari un incentivo sui volumi recuperati, e provare ad andare a caccia delle aziende morose? Si \u00e8 mai provveduto. Dai tassi di recupero risibile pare di no.<\/p>\n<p>Dalla gestione finanziaria emergono le prime crepe. Per forza, dovendo liquidare le attivit\u00e0 in titoli per garantire la liquidit\u00e0 immediata per pagare le pensioni, i proventi finanziari si assottigliano. L\u2019anno scorso sono stati di pochi milioni solo 3,7, contro una media di qualche decina di milioni degli anni scorsi. Pesano anche le svalutazioni dei titoli. Nel 2019 sono stati persi 37 milioni e altri 14 milioni nel 2018. Altri 10 milioni sono stati persi nel 2020. Se i conferimenti immobiliari e la gestione in titoli avevano in passato compensato in parte il buco della previdenza, ora anche questo appiglio non c\u2019\u00e8 pi\u00f9. Un\u2019altra ragione per ritenere che la sopravvivenza dell\u2019Inpgi cos\u00ec com\u2019\u00e8 non \u00e8 garantita per nulla<\/p>\n<p>Il dissesto e l\u2019accumulo vertiginoso delle perdite non hanno scalfito pi\u00f9 di tanto gli stipendi del presidente Marina Macelloni e del direttore generale Mimma Iorio. Secondo l\u2019ultimo rapporto della Corte dei Conti, la presidente Macelloni nel 2017 ha incassato 229mila euro, cui si sono aggiunti 16mila euro di rimborsi per un totale di 246mila euro.<\/p>\n<p>Remunerazioni appena al di sotto del limite imposto per i dirigenti della pubblica amministrazione. Certo Macelloni ha fatto la sua piccola spending review dato che nel 2016 era arrivata a incassare 272 mila euro. Il direttore generale Mimma Iorio ha un contratto che le assicura una remunerazione fissa da 232 mila euro, al netto dei contribuiti previdenziali e assistenziali, come ha ricordato nell\u2019ultimo rapporto la Corte dei Conti.<\/p>\n<p>Nessuna auto-riforma potr\u00e0 invertire sul medio lungo termine la situazione. Sar\u00e0, come le ultime due riforme hanno dimostrato, un pannicello caldo utile solo a guadagnare tempo. Ma il tempo \u00e8 scaduto. Se l\u2019ipotesi del travaso dei comunicatori (unica chance che si \u00e8 data l\u2019Inpgi) fallir\u00e0 allora la fine \u00e8 segnata. Commissariamento inevitabile con i rischi questo s\u00ec di tagli draconiani. I giornalisti in pensione potrebbero ritrovarsi con la pensione sociale. Incaponirsi solo su questa linea vuol dire giocare a poker. Una scommessa sulla pelle dei giornalisti.<\/p>\n<p>L\u2019Inpdai ha gi\u00e0 percorso ormai pi\u00f9 di 15 anni fa la strada del rientro pubblico. I dirigenti d\u2019azienda vanno in pensione con le norme Inps, le stesse norme con cui l\u2019Inpgi con la riforma del 2017 si \u00e8 di fatto allineata. Per i trattamenti in essere dei dirigenti d\u2019azienda prima del passaggio all\u2019Inps provvede la gestione speciale ex Inpdai. Paga le pensioni non incassando pi\u00f9 contributi. Solo il cappello pubblico consente di provvedere al pagamento delle pensioni. Se si fallisce da privati allora non c\u2019\u00e8 pi\u00f9 nessun ombrello. Perch\u00e9 pu\u00f2 valere per i dirigenti d\u2019azienda e per i giornalisti l\u2019ipotesi di una ripubblicizzazione pare ancora un tab\u00f9? Si attendono risposte non retoriche.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Via Dagospia Niente e nessuno potr\u00e0 salvare l\u2019Inpgi, l\u2019ente di previdenza dei giornalisti privatizzato nel lontano \u201994, dal dissesto definitivo. Solo un ritorno sotto le ali dell\u2019Inps, come fecero i dirigenti d\u2019azienda nel 2003 quando i conti del loro ente privatizzato, l\u2019Inpdai, mostravano un deficit di 600 milioni, potr\u00e0 garantire la sostenibilit\u00e0 nel lungo periodo &#8230; <a title=\"Dagospia e l&#8217;eutanasia dell&#8217;INPGI\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2021\/01\/14\/dagospia-e-leutanasia-dellinpgi\/\" aria-label=\"Per saperne di pi\u00f9 su Dagospia e l&#8217;eutanasia dell&#8217;INPGI\">Leggi tutto<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[424],"tags":[],"class_list":["post-35243","post","type-post","status-publish","format-standard","hentry","category-personale"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/35243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=35243"}],"version-history":[{"count":1,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/35243\/revisions"}],"predecessor-version":[{"id":35244,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/35243\/revisions\/35244"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=35243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=35243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=35243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}