{"id":4203,"date":"2008-07-27T17:51:56","date_gmt":"2008-07-27T16:51:56","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=4203"},"modified":"2008-12-19T08:05:14","modified_gmt":"2008-12-19T07:05:14","slug":"informazioni-mezzo-stampa-su-lastampait","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2008\/07\/27\/informazioni-mezzo-stampa-su-lastampait\/","title":{"rendered":"Informazioni contrattuali a mezzo stampa episodio 2"},"content":{"rendered":"<p>Dopo <a href=\"http:\/\/www.pasteris.it\/blog\/2008\/05\/07\/i-corallini-di-lastampait\/\">un primo caso<\/a> nuovamente si scoprono cose sul proprio status professionale leggendo dai giornali<\/p>\n<p>Da Prima Comunicazione di luglio &#8211; agosto 2008<\/p>\n<blockquote><p>Il direttore della Stampa Giulio Anselmi ha deciso di riorganizzare la redazione internet e con questo obiettivo ha trasferito Dario Corradino dall&#8217;ufficio dei caporedattori centrali alla Stampa.it.<br \/>\nIn pratica si tratta di un ritorno, visto che Corradino ha lavorato gi\u00e0\u00a0 cinque anni fa alla redazione della Stampa.it guidata da Anna Masera (\u00e8 lei che ha messo in piedi l&#8217;edizione sul web del quotidiano torinese) e dove lavora anche Carla Reschia, oltre a una decina di collaboratori, tra cui alcuni tecnici.<br \/>\nUn accordo fra la direzione e il Cdr della Stampa prevede di rinforzare il web, con quattro assunzioni con contratto giornalistico entro l&#8217;anno, a cui se ne aggiungeranno altre due nel 2009.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Dopo un primo caso nuovamente si scoprono cose sul proprio status professionale leggendo dai giornali Da Prima Comunicazione di luglio &#8211; agosto 2008 Il direttore della Stampa Giulio Anselmi ha deciso di riorganizzare la redazione internet e con questo obiettivo ha trasferito Dario Corradino dall&#8217;ufficio dei caporedattori centrali alla Stampa.it. In pratica si tratta di &#8230; <a title=\"Informazioni contrattuali a mezzo stampa episodio 2\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2008\/07\/27\/informazioni-mezzo-stampa-su-lastampait\/\" aria-label=\"Per saperne di pi\u00f9 su Informazioni contrattuali a mezzo stampa episodio 2\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,30,14],"tags":[475,159,161,193,474,2160],"class_list":["post-4203","post","type-post","status-publish","format-standard","hentry","category-diritti","category-media","category-torino","tag-corradino","tag-giornali","tag-giornalisti","tag-lastampa","tag-masera","tag-torino"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/4203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=4203"}],"version-history":[{"count":12,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/4203\/revisions"}],"predecessor-version":[{"id":7278,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/4203\/revisions\/7278"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=4203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=4203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=4203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}