{"id":522,"date":"2006-08-22T11:06:50","date_gmt":"2006-08-22T09:06:50","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/archives\/522"},"modified":"2006-08-10T18:08:59","modified_gmt":"2006-08-10T16:08:59","slug":"per-non-dimenticare-il-passato","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2006\/08\/22\/per-non-dimenticare-il-passato\/","title":{"rendered":"Per non dimenticare il passato"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"319\" height=\"81\" align=\"right\" src=\"http:\/\/www.storiaolivetti.telecomitalia.it\/Imgs\/societa\/Manifesti_composizioneLogo.jpg\" \/>Nel panorama dell\u2019industria italiana e mondiale Olivetti                           si \u00e8 sempre distinta per il suo particolare stile aziendale:                           uno stile basato sull\u2019eccellenza tecnologica, l\u2019innovazione,                           la qualit\u00e0 e il design, il rispetto del mercato, ma                           anche su un forte impegno a favore dell\u2019arte e della                           cultura, sulla sensibilit\u00e0 verso i problemi sociali                           e verso il costante miglioramento del rapporto con i                           dipendenti e il territorio.<\/p>\n<p><a href=\"http:\/\/www.storiaolivetti.telecomitalia.it\">www.storiaolivetti.telecomitalia.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel panorama dell\u2019industria italiana e mondiale Olivetti si \u00e8 sempre distinta per il suo particolare stile aziendale: uno stile basato sull\u2019eccellenza tecnologica, l\u2019innovazione, la qualit\u00e0 e il design, il rispetto del mercato, ma anche su un forte impegno a favore dell\u2019arte e della cultura, sulla sensibilit\u00e0 verso i problemi sociali e verso il costante miglioramento &#8230; <a title=\"Per non dimenticare il passato\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2006\/08\/22\/per-non-dimenticare-il-passato\/\" aria-label=\"Per saperne di pi\u00f9 su Per non dimenticare il passato\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[415,534,178,61,437,250],"class_list":["post-522","post","type-post","status-publish","format-standard","hentry","tag-arte","tag-cultura","tag-innovazione","tag-italia","tag-mondiale","tag-olivetti"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=522"}],"version-history":[{"count":0,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/522\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}