{"id":5470,"date":"2008-09-29T16:47:43","date_gmt":"2008-09-29T14:47:43","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=5470"},"modified":"2008-09-29T21:24:53","modified_gmt":"2008-09-29T19:24:53","slug":"citta-di-torino-wifi-area-finalmente-una-vera-torino-wireless","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2008\/09\/29\/citta-di-torino-wifi-area-finalmente-una-vera-torino-wireless\/","title":{"rendered":"Citt\u00e0 di Torino Wifi area: finalmente una vera Torino wireless ?"},"content":{"rendered":"<p>Da qualche giorno sono comparsi in giro per Torino degli hotspot targati <em><a href=\"http:\/\/www.comune.torino.it\/\">Citt\u00e0 di Torino<\/a> &#8211; wifi area\u00a0 Powered by <a href=\"http:\/\/www.aemnet.torino.it\">AemNet <\/a><\/em>.<\/p>\n<p>Al tentativo di connessione compare una maschera che chiede login e password per accedere al servizio.<\/p>\n<p>Forse si tratta finalmente della fase operativa di un <a href=\"http:\/\/www.comune.torino.it\/ucstampa\/2006\/article_489.shtml\">progetto presentato ben due anni fa<\/a> per una copertura wireless della citt\u00e0 da parte del Comune. La presenza degli hotspot fa ben sperare che l&#8217;iniizativa possa finalmente partire.<\/p>\n<p><a href=\"http:\/\/www.pasteris.it\/blog\/wp-content\/uploads\/2008\/09\/wifiarea-torino.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5474\" title=\"wifiarea-torino\" src=\"http:\/\/www.pasteris.it\/blog\/wp-content\/uploads\/2008\/09\/wifiarea-torino.jpg\" alt=\"\" width=\"500\" height=\"270\" \/><\/a><\/p>\n<p>Qualcuno ne sa qualche cosa di pi\u00f9?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da qualche giorno sono comparsi in giro per Torino degli hotspot targati Citt\u00e0 di Torino &#8211; wifi area\u00a0 Powered by AemNet . Al tentativo di connessione compare una maschera che chiede login e password per accedere al servizio. Forse si tratta finalmente della fase operativa di un progetto presentato ben due anni fa per una &#8230; <a title=\"Citt\u00e0 di Torino Wifi area: finalmente una vera Torino wireless ?\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2008\/09\/29\/citta-di-torino-wifi-area-finalmente-una-vera-torino-wireless\/\" aria-label=\"Per saperne di pi\u00f9 su Citt\u00e0 di Torino Wifi area: finalmente una vera Torino wireless ?\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[2160],"class_list":["post-5470","post","type-post","status-publish","format-standard","hentry","tag-torino"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/5470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=5470"}],"version-history":[{"count":4,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/5470\/revisions"}],"predecessor-version":[{"id":5472,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/5470\/revisions\/5472"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=5470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=5470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=5470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}