{"id":6162,"date":"2008-11-05T14:15:12","date_gmt":"2008-11-05T12:15:12","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=6162"},"modified":"2008-11-05T21:37:39","modified_gmt":"2008-11-05T19:37:39","slug":"fantozzi-al-maria-vittoria","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2008\/11\/05\/fantozzi-al-maria-vittoria\/","title":{"rendered":"Fantozzi al Maria Vittoria"},"content":{"rendered":"<p>L&#8217;attesa<a href=\"http:\/\/www.pasteris.it\/blog\/2008\/11\/03\/residence-maria-vittoria\/\"> operazione al naso<\/a> \u00e8 stata definitvamente rinviata a met\u00e0 novembre dopo un primo rinvio parziale. Evidentemente al Maria Vittoria hanno un sacco di pazienti con grossi problemi alla testa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;attesa operazione al naso \u00e8 stata definitvamente rinviata a met\u00e0 novembre dopo un primo rinvio parziale. Evidentemente al Maria Vittoria hanno un sacco di pazienti con grossi problemi alla testa.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[2157],"class_list":["post-6162","post","type-post","status-publish","format-standard","hentry","tag-blog"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/6162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=6162"}],"version-history":[{"count":2,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/6162\/revisions"}],"predecessor-version":[{"id":6165,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/6162\/revisions\/6165"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=6162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=6162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=6162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}