{"id":6466,"date":"2008-11-28T08:38:45","date_gmt":"2008-11-28T06:38:45","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=6466"},"modified":"2008-11-24T09:30:47","modified_gmt":"2008-11-24T07:30:47","slug":"dio-google","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2008\/11\/28\/dio-google\/","title":{"rendered":"Dio Google"},"content":{"rendered":"<p><a href=\"http:\/\/dragor.blog.lastampa.it\/journal_intime\/2008\/11\/google-e-dio-1.html\">Via Journal in time<\/a><\/p>\n<blockquote><p>\n<img decoding=\"async\" class=\"alignright\" src=\"http:\/\/dragor.blog.lastampa.it\/journal_intime\/images\/2008\/11\/18\/tttttttttttttttttttgooglegod.jpg\" alt=\"\" \/>Noi della Chiesa di Google crediamo che il motore di ricerca Google sia il vero Dio. Crediamo che ci siano pi\u00f9 prove per la divinit\u00e0 di Google che per quella di tutti gli altri dei, da noi rifiutati perch\u00e9 non si pu\u00f2 scientificamente provare la loro esistenza. Noi Googliani crediamo che Google meriti il titolo di Dio perch\u00e9 la Sua divinit\u00e0 \u00e8 scientificamente dimostrabile.<\/p><\/blockquote>\n<blockquote><p>Ecco 9 prove per dimostrare che Google \u00e8 Dio.<br \/>\nGoogle \u00e8 Onnisciente e si pu\u00f2 dimostrarlo scientificamente<br \/>\nGoogle \u00e8 Onnipresente<br \/>\nGoogle risponde alle preghiere<br \/>\nGoogle \u00e8 immortale<br \/>\nGoogle \u00e8 infinito<br \/>\nGoogle ricorda tutto<br \/>\nGoogle \u00e8 buono<br \/>\nSecondo i Trend di Google, la parola \u201cGoogle\u201d \u00e8 da sola pi\u00f9 ricercata delle parole Dio, Ges\u00f9, Allah, Budda, Cristianesimo, Islam, Buddismo e Giudaismo tutte insieme.<br \/>\nLe prove dell\u2019esistenza di Google sono numerose. Ci sono pi\u00f9 prove per l\u2019esistenza di Google che per quella di ogni altro Dio<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Via Journal in time Noi della Chiesa di Google crediamo che il motore di ricerca Google sia il vero Dio. Crediamo che ci siano pi\u00f9 prove per la divinit\u00e0 di Google che per quella di tutti gli altri dei, da noi rifiutati perch\u00e9 non si pu\u00f2 scientificamente provare la loro esistenza. Noi Googliani crediamo che &#8230; <a title=\"Dio Google\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2008\/11\/28\/dio-google\/\" aria-label=\"Per saperne di pi\u00f9 su Dio Google\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[2157,162,193,286],"class_list":["post-6466","post","type-post","status-publish","format-standard","hentry","tag-blog","tag-google","tag-lastampa","tag-ricerca"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/6466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=6466"}],"version-history":[{"count":3,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/6466\/revisions"}],"predecessor-version":[{"id":6502,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/6466\/revisions\/6502"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=6466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=6466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=6466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}