{"id":6623,"date":"2008-12-02T10:03:40","date_gmt":"2008-12-02T08:03:40","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=6623"},"modified":"2008-12-02T10:03:40","modified_gmt":"2008-12-02T08:03:40","slug":"il-paradiso-del-social-engineering","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2008\/12\/02\/il-paradiso-del-social-engineering\/","title":{"rendered":"Il paradiso del social engineering"},"content":{"rendered":"<p>Via <a href=\"http:\/\/xmau.com\/notiziole\/arch\/200810\/004888.html\">Maurizio Codogno<\/a><\/p>\n<blockquote><p>La mia personale opinione \u00e8 che Facebook sia l&#8217;esperimento meglio riuscito di social engineering su scala planetaria. Per chi non lo sapesse, il social engineering \u00e8 il modo pi\u00f9 semplice per ottenere informazioni segrete. Crederete mica che i cracker e gli hacker abbiano fatto attacchi bruta forza per penetrare nei sistemi? Figuriamoci. \u00c8 molto pi\u00f9 semplice ricavare la password direttamente dalla persona stessa, magari chiacchierando un po&#8217; e facendo in modo che ti dia implicitamente degli indizi. Facebook \u00e8 appunto l&#8217;estensione di questo concetto. Ti senti invogliato a riempire il tuo profilo parlando di te, perch\u00e9 cos\u00ec i tuoi amici ti possono trovare. (Tra l&#8217;altro, nota che il profilo non fa parte dei setting, cio\u00e8 la parte che viene tipicamente vista come &#8220;la sicurezza&#8221;). Ti senti invogliato ad accettare tanti amici, perch\u00e9 cos\u00ec ti puoi mantenere in contatto con loro. Addirittura, non appena qualcuno ti manda un messaggio attraverso un&#8217;applicazione &#8211; e questo \u00e8 cos\u00ec facile, visto che te lo fa fare di default &#8211; tu sei pronto a dare tutti gli accessi in lettura a questa applicazione. E lo fai volontariamente. Il paradiso per un social engineer, non c&#8217;\u00e8 che dire.<br \/>\n<!--more--><br \/>\nIo non sono cos\u00ec paranoico. Come ho scritto, i dati che ho fornito sono parecchi e tutti rigorosamente veri. Per\u00f2 sono tutti dati che non mi d\u00e0 fastidio riportare, anche in un unico posto il che permette di fare molta fatica in meno a radunarli. D&#8217;altra parte, basta leggere il mio blog per avere una quantit\u00e0 simile se non maggiore di informazioni su di me, quindi non \u00e8 che ci perda cos\u00ec tanto :-) Il guaio \u00e8 pi\u00f9 che altro per chi non \u00e8 abituato a questa perdita di intimit\u00e0 nell&#8217;Era della Rete (e poi magari piange perch\u00e9 pretende il diritto all&#8217;oblio&#8230;); inoltre non so cosa potrebbe succedere con un&#8217;applicazione meme che per\u00f2 ricavi abbastanza dati per fare un profilo demografico di un numero davvero grande di persone.<br \/>\nSe io dovessi rivedere il modello di Facebook, credo che lo farei &#8220;a cipolla&#8221;: non definirei solo amici ma anche contatti, conoscenti, colleghi, familiari, intimi; renderei impossibile sapere a quale categoria appartiene una persona (un &#8220;contatto&#8221; non pu\u00f2 vedere direttamente nulla, un &#8220;conoscente&#8221; vede amici colleghi familiari intimi tutti come &#8220;conoscenti&#8221;, e cos\u00ec via), e per ogni dato lascerei la scelta di indicare fino a che categoria renderlo pubblico, con default &#8220;a nessuno&#8221;. Ma so anche che un modello del genere non avrebbe mai avuto successo: il bello del social engineering \u00e8 proprio che funziona proprio perch\u00e9 \u00e8 il tapino stesso che vuole cos\u00ec, come del resto tutte le truffe anche nella vita reale. Quindi teniamoci Facebook cos\u00ec com&#8217;\u00e8; e svegliamoci, non sveliamoci!<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Via Maurizio Codogno La mia personale opinione \u00e8 che Facebook sia l&#8217;esperimento meglio riuscito di social engineering su scala planetaria. Per chi non lo sapesse, il social engineering \u00e8 il modo pi\u00f9 semplice per ottenere informazioni segrete. Crederete mica che i cracker e gli hacker abbiano fatto attacchi bruta forza per penetrare nei sistemi? Figuriamoci. &#8230; <a title=\"Il paradiso del social engineering\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2008\/12\/02\/il-paradiso-del-social-engineering\/\" aria-label=\"Per saperne di pi\u00f9 su Il paradiso del social engineering\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[415,2157,118,129,168,551,306,430],"class_list":["post-6623","post","type-post","status-publish","format-standard","hentry","tag-arte","tag-blog","tag-ebook","tag-facebook","tag-hacker","tag-legge","tag-sicurezza","tag-truffe"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/6623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=6623"}],"version-history":[{"count":1,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/6623\/revisions"}],"predecessor-version":[{"id":6624,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/6623\/revisions\/6624"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=6623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=6623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=6623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}