{"id":821,"date":"2006-10-27T16:21:39","date_gmt":"2006-10-27T14:21:39","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/archives\/821"},"modified":"2006-10-27T16:21:39","modified_gmt":"2006-10-27T14:21:39","slug":"in-diretta-da-orvieto-dal-congresso-anso","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2006\/10\/27\/in-diretta-da-orvieto-dal-congresso-anso\/","title":{"rendered":"In diretta da Orvieto dal congresso ANSO"},"content":{"rendered":"<p>Da Orvieto con <a href=\"http:\/\/www.pandemia.info\" target=\"_blank\">Luca Conti<\/a> dalle ore 15 trasmissione con Stickam del convegno aperto al pubblico in occasione della terza assemblea nazionale dell&#8217;ANSO. Il tema del convegno sar\u00e0: I nuovi attori dell&#8217;informazione. Come cambia la produzione delle notizie tra stampa online e blog.<\/p>\n<p><a href=\"http:\/\/www.pasteris.it\/blog\/media\/stickam.html\" target=\"_blank\">Il link per seguire la trasmissione live con Stickam<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da Orvieto con Luca Conti dalle ore 15 trasmissione con Stickam del convegno aperto al pubblico in occasione della terza assemblea nazionale dell&#8217;ANSO. Il tema del convegno sar\u00e0: I nuovi attori dell&#8217;informazione. Come cambia la produzione delle notizie tra stampa online e blog. Il link per seguire la trasmissione live con Stickam<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[2157,176,2168],"class_list":["post-821","post","type-post","status-publish","format-standard","hentry","tag-blog","tag-informazione","tag-media"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=821"}],"version-history":[{"count":0,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/821\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}