{"id":9648,"date":"2009-04-02T18:05:31","date_gmt":"2009-04-02T17:05:31","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=9648"},"modified":"2009-04-02T03:11:24","modified_gmt":"2009-04-02T02:11:24","slug":"fare-casino-evidentemente-serve","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2009\/04\/02\/fare-casino-evidentemente-serve\/","title":{"rendered":"Fare casino evidentemente serve"},"content":{"rendered":"<p>A proposito della <a href=\"http:\/\/www.pasteris.it\/blog\/2009\/04\/01\/combattere-per-una-villareggia-a-banda-larga\/\">battaglia per l&#8217;adsl a Villareggia<\/a>. <a href=\"http:\/\/abandastretta.blogspot.com\/2007\/03\/la-mappa-dei-comuni-banda-stretta-della.html\">Vische paese vicino e di pari caratteristiche rimase escluso dai primi piani di connessione<\/a>. <a href=\"http:\/\/espresso.repubblica.it\/dettaglio-local\/%C2%ABIngiusto-escluderci-dalla--banda-larga-%C2%BB\/1536333\">Poi i locali iniziarono a fare casino<\/a>.<\/p>\n<blockquote><p>Esclusa, insieme ad altri quindici comuni del Canavese dalla cosiddetta \u2018banda larga\u2019, Vische insorge. A protestare per primo \u00e8 il sindaco Mario Pignochino, che gi\u00e0 alcuni mesi fa aveva ospitato un tecnico esperto nell\u2019utilizzo delle nuove tecnologia wireless e digitali proprio per affrontare e capire i problemi relativi all\u2019installazione della fibra ottica.<br \/>\n\u00abChe senso ha &#8211; esordisce il primo cittadino &#8211; parlare di \u2018Piano strategico\u2019, avviare nuove iniziative per facilitare la nascita di nuovi insediamenti produttivi in Canavese, fornire alle aziende operanti sul territorio strumenti per ammodernare i propri modelli organizzativi e gestionali, se poi si tagliano fuori dal progresso alcuni Comuni come il nostro? Vische ha mille400 abitanti, ha una banca, diverse attivit\u00e0 imprenditoriali e commerciali, richieste di nuovi insediamenti, un\u2019amministrazione che vuol essere al passo con i tempi. Perch\u00e9 &#8211; si domanda il sindaco &#8211; dobbiamo essere esclusi dall\u2019utilizzo della linea ADSL che, oltre ad accelerare i tempi riduce i costi, con la garanzia di un perfetto collegamento? Siamo a met\u00e0 strada tra Caluso e Strambino, gi\u00e0 serviti dalla banda larga. Per cui non credo sia poi cos\u00ec oneroso estendere il servizio anche a Vische\u00bb.<br \/>\nAlla protesta del sindaco si aggiunge quella della popolazione. Nei giorni scorsi, su iniziativa di un comitato spontaneo, \u00e8 partita una raccolta firma per chiedere alla Telecom l\u2019istallazione dell\u2019ADSL. In pochi giorni, si sono raccolte quasi mille firme che sabato scorso sono state consegnate al sindaco.<\/p><\/blockquote>\n<p>Ora Vische \u00e8 connesso all&#8217;Adsl<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A proposito della battaglia per l&#8217;adsl a Villareggia. Vische paese vicino e di pari caratteristiche rimase escluso dai primi piani di connessione. Poi i locali iniziarono a fare casino. Esclusa, insieme ad altri quindici comuni del Canavese dalla cosiddetta \u2018banda larga\u2019, Vische insorge. A protestare per primo \u00e8 il sindaco Mario Pignochino, che gi\u00e0 alcuni &#8230; <a title=\"Fare casino evidentemente serve\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2009\/04\/02\/fare-casino-evidentemente-serve\/\" aria-label=\"Per saperne di pi\u00f9 su Fare casino evidentemente serve\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[424],"tags":[62,115,357],"class_list":["post-9648","post","type-post","status-publish","format-standard","hentry","category-personale","tag-banda-larga","tag-digital-divide","tag-villareggia"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/9648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=9648"}],"version-history":[{"count":1,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/9648\/revisions"}],"predecessor-version":[{"id":9649,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/9648\/revisions\/9649"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=9648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=9648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=9648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}