{"id":9909,"date":"2009-04-14T16:36:40","date_gmt":"2009-04-14T15:36:40","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=9909"},"modified":"2009-04-14T16:36:40","modified_gmt":"2009-04-14T15:36:40","slug":"parole-di-speranza-e-segnali-di-fiducia","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2009\/04\/14\/parole-di-speranza-e-segnali-di-fiducia\/","title":{"rendered":"Parole di speranza e segnali di fiducia"},"content":{"rendered":"<p><a href=\"http:\/\/www.ilbarbieredellasera.com\/article.php?sid=17127\">Via Il Barbiere della Sera<\/a><\/p>\n<blockquote><p><span class=\"art\">Pare che la FNSI, incoraggiata dalla disponibilit\u00e0 mostrata degli editori sul rinnovo del contratto giornalistico, voglia intervenire anche sul terreno della deontologia, erogando un &#8220;codice etico&#8221; per l&#8217;Emergenza Terremoto. In un libello che verr\u00e0 diffuso nelle prossime ore si raccomanda agli inviati:<br \/>\n1) di astenersi dalla domanda &#8220;CHE COSA PROVA IN QUESTO MOMENTO&#8221; se si tratta di persone che non si sono ancora liberate dai calcinacci o siano in evidente stato di shock<\/span><span class=\"art\"><br \/>\n2) di non svegliare dopo le 24 i terremotati che dormano all&#8217;addiaccio, nelle tendopli o nelle auto<br \/>\n<\/span><span class=\"art\">3) di evitare frasi tipo &#8220;SIAMO QUI A NOSTRO RISCHIO E PERICOLO&#8221;, per rispetto ai soccorritori<br \/>\n<\/span><span class=\"art\">4) di non riscuotere\u00a0 &#8220;parole di speranza&#8221; o &#8220;segnali di fiducia&#8221; dal primo malcapitato che cada nella rete delle dirette<br \/>\n<\/span><span class=\"art\">5) di dare, nel calcolo dei danni, la priorit\u00e0 alle chiese distrutte, ricordando pero&#8217;, a margine, le molte migliaia di edifici laici<br \/>\n6) di celebrare gli indici d&#8217;ascolto solo quando le scosse di assestamento della Rai (dette &#8220;NOMINE&#8221;) siano finite.<\/span><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Via Il Barbiere della Sera Pare che la FNSI, incoraggiata dalla disponibilit\u00e0 mostrata degli editori sul rinnovo del contratto giornalistico, voglia intervenire anche sul terreno della deontologia, erogando un &#8220;codice etico&#8221; per l&#8217;Emergenza Terremoto. In un libello che verr\u00e0 diffuso nelle prossime ore si raccomanda agli inviati: 1) di astenersi dalla domanda &#8220;CHE COSA PROVA &#8230; <a title=\"Parole di speranza e segnali di fiducia\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2009\/04\/14\/parole-di-speranza-e-segnali-di-fiducia\/\" aria-label=\"Per saperne di pi\u00f9 su Parole di speranza e segnali di fiducia\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,30],"tags":[161,499],"class_list":["post-9909","post","type-post","status-publish","format-standard","hentry","category-ironia","category-media","tag-giornalisti","tag-terremoto"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/9909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=9909"}],"version-history":[{"count":1,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/9909\/revisions"}],"predecessor-version":[{"id":9910,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/9909\/revisions\/9910"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=9909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=9909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=9909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}