{"id":9948,"date":"2009-04-16T08:11:13","date_gmt":"2009-04-16T07:11:13","guid":{"rendered":"http:\/\/www.pasteris.it\/blog\/?p=9948"},"modified":"2009-04-16T08:11:13","modified_gmt":"2009-04-16T07:11:13","slug":"google-un-miliardo-di-visitatori-ogni-mese-verso-gli-editori","status":"publish","type":"post","link":"https:\/\/www.pasteris.it\/blog\/2009\/04\/16\/google-un-miliardo-di-visitatori-ogni-mese-verso-gli-editori\/","title":{"rendered":"Google: un miliardo di visitatori ogni mese verso gli editori"},"content":{"rendered":"<p><a href=\"http:\/\/www.lsdi.it\/2009\/04\/11\/google-un-miliardo-di-visitatori-ogni-mese-verso-i-siti-degli-editori\/\">Via Lsdi<\/a><\/p>\n<div class=\"post-content\">\n<p><img decoding=\"async\" class=\"alignright\" src=\"http:\/\/www.realgeek.com\/wp-content\/uploads\/2007\/03\/google-logo.jpg\" alt=\"Google\" \/><\/p>\n<blockquote><p>Mentre continua ad infuriare la discussione sul presunto parassitismo di Google rispetto ai produttori di informazione giornalistica (gli editori della carta stampata soprattutto), il servizio giuridico del gigante di Mountain View <a href=\"http:\/\/googlepublicpolicy.blogspot.com\/2009\/04\/some-questions-related-to-google-news.html\">diffonde<\/a> una informazione interessante: Google <a href=\"http:\/\/googlepublicpolicy.blogspot.com\/2009\/04\/some-questions-related-to-google-news.html\">invia  ogni mese un miliardo di visite<\/a> (e  cio\u00e8 il \u00a0<a href=\"http:\/\/media-tech.blogspot.com\/2009\/04\/une-epoque-formidable-ou-terrifiante.html\">3%  della sua attivit\u00e0 di ricerca<\/a>) dai suoi siti a quelli degli editori.<\/p>\n<p>Questo \u2013 secondo il blog francese <a href=\"http:\/\/media-tech.blogspot.com\/2009\/04\/google-un-milliard-de-visites-vers-les.html\">Media-tech<\/a> \u2013 conferirebbe a Google una fortissimo potere di fronte agli editori per due  motivi:<\/p>\n<p>&#8211; inva loro un traffico massiccio: e quindi \u00e8 perfettamente riuscita la sua <a href=\"http:\/\/media-tech.blogspot.com\/2008\/05\/google-news-la-saga-belge.html\">&#8220;Reintermediazione  del Quarto potere&#8221;<\/a><br \/>\n&#8211;  e poi d\u00e0 loro, tramite <a href=\"http:\/\/media-tech.blogspot.com\/2008\/04\/google-via-doubleclick-domine.html\">AdSense  ou Doubleclick<\/a>, un doppio mezzo per monetizzare questo traffico che dirotta  nella loro direzione.<\/p>\n<p>Chi oser\u00e0 ribellarsi? Gli editori che <a href=\"http:\/\/media-tech.blogspot.com\/2008\/05\/google-news-la-saga-belge.html\">hanno  cercato di farlo in passato hanno dovuto ripensarci<\/a>: avevano troppo da perdere a breve termine (calo di audience). E la crisi attuale lascia loro ancora meno margini di manovra.<\/p><\/blockquote>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Via Lsdi Mentre continua ad infuriare la discussione sul presunto parassitismo di Google rispetto ai produttori di informazione giornalistica (gli editori della carta stampata soprattutto), il servizio giuridico del gigante di Mountain View diffonde una informazione interessante: Google invia ogni mese un miliardo di visite (e cio\u00e8 il \u00a03% della sua attivit\u00e0 di ricerca) dai &#8230; <a title=\"Google: un miliardo di visitatori ogni mese verso gli editori\" class=\"read-more\" href=\"https:\/\/www.pasteris.it\/blog\/2009\/04\/16\/google-un-miliardo-di-visitatori-ogni-mese-verso-gli-editori\/\" aria-label=\"Per saperne di pi\u00f9 su Google: un miliardo di visitatori ogni mese verso gli editori\">Leggi tutto<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,30],"tags":[159,162],"class_list":["post-9948","post","type-post","status-publish","format-standard","hentry","category-internet","category-media","tag-giornali","tag-google"],"_links":{"self":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/9948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/comments?post=9948"}],"version-history":[{"count":2,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/9948\/revisions"}],"predecessor-version":[{"id":9950,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/posts\/9948\/revisions\/9950"}],"wp:attachment":[{"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/media?parent=9948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/categories?post=9948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pasteris.it\/blog\/wp-json\/wp\/v2\/tags?post=9948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}